{"id":14430,"date":"2025-06-09T11:30:39","date_gmt":"2025-06-09T04:30:39","guid":{"rendered":"https:\/\/champameuanglao.com\/?p=14430"},"modified":"2025-06-09T11:32:39","modified_gmt":"2025-06-09T04:32:39","slug":"18-provinces-in-laos-what-do-they-mean-2","status":"publish","type":"post","link":"https:\/\/champameuanglao.com\/la\/18-provinces-in-laos-what-do-they-mean-2\/","title":{"rendered":"\u0ead\u0eb0\u0e97\u0eb4\u0e9a\u0eb2\u0e8d\u0e84\u0ea7\u0eb2\u0ea1\u0edd\u0eb2\u0e8d\u0e82\u0ead\u0e87\u0e8a\u0eb7\u0ec8\u0e97\u0eb1\u0e87 18 \u0ec1\u0e82\u0ea7\u0e87\u0ec3\u0e99\u0e9b\u0eb0\u0ec0\u0e97\u0e94\u0ea5\u0eb2\u0ea7"},"content":{"rendered":"<p><\/p>\n<p class=\"p1\"><i><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14442\" src=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Vientiane-2-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Vientiane-2-scaled.jpg 2560w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Vientiane-2-300x200.jpg 300w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Vientiane-2-1024x683.jpg 1024w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Vientiane-2-768x512.jpg 768w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Vientiane-2-1536x1024.jpg 1536w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Vientiane-2-2048x1365.jpg 2048w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Vientiane-2-630x420.jpg 630w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Vientiane-2-150x100.jpg 150w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Vientiane-2-696x464.jpg 696w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Vientiane-2-1068x712.jpg 1068w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Vientiane-2-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/> \u0eae\u0ea7\u0e9a\u0eae\u0ec8\u0ea7\u0ea1 \u0ec1\u0ea5\u0eb0 \u0e84\u0ebb\u0ec9\u0e99\u0e84\u0ea7\u0ec9\u0eb2\u0ec2\u0e94\u0e8d: \u0e97\u0ec9\u0eb2\u0ea7 \u0ea7\u0eb4\u0ea5\u0eb0 \u0e9e\u0eb9\u0ec8\u0e99\u0ea7\u0ebb\u0e87\u0eaa\u0eb2 \/ Sna\u00e9 History<\/i><\/p>\n<p class=\"p1\"><i>\u0eae\u0eb9\u0e9a\u0ec2\u0e94\u0e8d: \u0e9e\u0eb9\u0e99\u0e8a\u0eb1\u0e9a \u0ec0\u0e97\u0ea7\u0ebb\u0e87\u0eaa\u0eb2<\/i><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><b>1. \u0ec1\u0e82\u0ea7\u0e87 \u0eab\u0ebc\u0ea7\u0e87\u0e9e\u0ea3\u0eb0\u0e9a\u0eb2\u0e87<\/b><\/p>\n<p class=\"p2\">\u0e84\u0ea7\u0eb2\u0ea1\u0edd\u0eb2\u0e8d\u0e97\u0eb2\u0e87\u0e94\u0ec9\u0eb2\u0e99\u0e84\u0eb3\u0eaa\u0eb1\u0e9a: \u201c\u0eab\u0ebc\u0ea7\u0e87\u201d \u0ec3\u0e99\u0e9e\u0eb2\u0eaa\u0eb2\u0ea5\u0eb2\u0ea7\u0edd\u0eb2\u0e8d\u0ec0\u0e96\u0eb4\u0e87 \u201c\u0ec3\u0eab\u0e8d\u0ec8\u201d \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0eab\u0e8d\u0ecd\u0ec9\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e84\u0eb3\u0ea7\u0ec8\u0eb2\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0eab\u0ebc\u0ea7\u0e87 \u0eab\u0ebc\u0eb7 \u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ec3\u0eab\u0e8d\u0ec8, \u0e9e\u0ea3\u0eb0\u0e9a\u0eb2\u0e87\u0ec1\u0ea1\u0ec8\u0e99\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e8a\u0eb7\u0ec8\u0e9e\u0ea3\u0eb0\u0e9e\u0eb8\u0e94\u0e97\u0eb0\u0eae\u0eb9\u0e9a\u0e84\u0eb9\u0ec8\u0e9a\u0ec9\u0eb2\u0e99\u0e84\u0eb9\u0ec8\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e82\u0ead\u0e87\u0ead\u0eb2\u0e99\u0eb2\u0e88\u0eb1\u0e81\u0ea5\u0ec9\u0eb2\u0e99\u0e8a\u0ec9\u0eb2\u0e87 \u0ea5\u0ea7\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0ec1\u0ea5\u0ec9\u0ea7 \u201c\u0eab\u0ebc\u0ea7\u0e87\u0e9e\u0ea3\u0eb0\u0e9a\u0eb2\u0e87\u201d \u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0eab\u0ebc\u0ea7\u0e87 \u0eab\u0ebc\u0eb7 \u201c\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ec3\u0eab\u0e8d\u0ec8\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0e9e\u0ea3\u0eb0\u0e9a\u0eb2\u0e87\u0eaa\u0eb0\u0e96\u0eb4\u0e94\u0ea2\u0eb9\u0ec8\u201d \u0e8a\u0eb7\u0ec8\u0e99\u0eb5\u0ec9\u0ec3\u0e8a\u0ec9\u0ea1\u0eb2\u0ec1\u0e95\u0ec8\u0e9b\u0eb5 \u0e84.\u0eaa 1560.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><b>2. \u0ec1\u0e82\u0ea7\u0e87 \u0e8a\u0ebd\u0e87\u0e82\u0ea7\u0eb2\u0e87<\/b><\/p>\n<p class=\"p2\">\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0e8a\u0ebd\u0e87\u201d \u0ec3\u0e99\u0e9e\u0eb2\u0eaa\u0eb2\u0ea5\u0eb2\u0ea7\u0ec1\u0ea1\u0ec8\u0e99\u0ea1\u0eb5\u0ec0\u0e84\u0ebb\u0ec9\u0eb2\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u0eaa\u0ec9\u0ebd\u0e99 \u0eab\u0ebc\u0eb7 \u0eaa\u0ebd\u0e99 \u0ec3\u0e99\u0e9e\u0eb2\u0eaa\u0eb2\u0e88\u0eb5\u0e99 \u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u0ec0\u0ea1\u0eb7\u0ead\u0e87 \u0eab\u0ebc\u0eb7 \u0e8a\u0eb8\u0ea1\u0e8a\u0ebb\u0e99\u0ec3\u0eab\u0e8d\u0ec8, \u0eaa\u0ec8\u0ea7\u0e99\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0e82\u0ea7\u0eb2\u0e87\u201d \u0ec3\u0e99\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0e8a\u0ebd\u0e87\u0e82\u0ea7\u0eb2\u0e87\u201d \u0ec1\u0ea1\u0ec8\u0e99\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0e81\u0ea7\u0ec9\u0eb2\u0e87\u0e82\u0ea7\u0eb2\u0e87\u201d \u0ea5\u0ea7\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0ec1\u0ea5\u0ec9\u0ea7\u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ec3\u0eab\u0e8d\u0ec8 \u0eab\u0ebc\u0eb7 \u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e97\u0eb5\u0ec8\u0e81\u0ea7\u0ec9\u0eb2\u0e87\u0e82\u0ea7\u0eb2\u0e87 \u0e99\u0eb1\u0ec9\u0e99\u0ec0\u0ead\u0e87.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><b>3. \u0ec1\u0e82\u0ea7\u0e87 \u0ec4\u0e8a\u0e8d\u0eb0\u0e9a\u0eb9\u0ea5\u0eb5<\/b><\/p>\n<p class=\"p2\">\u201c\u0ec4\u0e8a\u0e8d\u0eb0\u201d \u0ea1\u0eb2\u0e88\u0eb2\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0e8a\u0eb1\u0e8d\u201d \u0e97\u0eb5\u0ec8\u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u0e84\u0ea7\u0eb2\u0ea1\u0e9c\u0eb2\u0e9a\u0ec1\u0e9e\u0ec9, \u0e84\u0ea7\u0eb2\u0ea1\u0e8a\u0eb0\u0e99\u0eb0<span class=\"Apple-converted-space\">\u00a0 <\/span>+\u00a0 \u0e9a\u0eb9\u0ea5\u0eb5 \u0e97\u0eb5\u0ec8\u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u0ec0\u0ea1\u0eb7\u0ead\u0e87 \u0ea5\u0ea7\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0ec1\u0ea5\u0ec9\u0ea7\u0ec1\u0ea1\u0ec8\u0e99\u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u201c\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ec1\u0eab\u0ec8\u0e87\u0ec4\u0e8a\u0e8a\u0eb0\u0e99\u0eb0\u201d \u0e99\u0eb1\u0ec9\u0e99\u0ec0\u0ead\u0e87, \u0e8a\u0eb7\u0ec8\u0e99\u0eb5\u0ec9\u0e96\u0eb7\u0e81\u0ec3\u0e8a\u0ec9\u0e9b\u0eb0\u0ea1\u0eb2\u0e99\u0eab\u0ebc\u0eb1\u0e87\u0e9b\u0eb5 \u0e84.\u0eaa 1946 \u0ec0\u0e9b\u0eb1\u0e99\u0e95\u0ebb\u0ec9\u0e99\u0ea1\u0eb2.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><b>4. \u0e9a\u0ecd\u0ec8\u0ec1\u0e81\u0ec9\u0ea7<\/b><\/p>\n<p class=\"p2\">\u0e84\u0ecd\u0eb2\u0ea7\u0ec8\u0eb2 \u201c\u0e9a\u0ecd\u0ec8\u201d \u0ec3\u0e99\u0e99\u0eb5\u0ec9\u0ec0\u0e9b\u0eb1\u0e99\u0e84\u0eb3\u0e99\u0eb2\u0ea1\u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u0ec1\u0eab\u0ebc\u0ec8\u0e87\u0e81\u0eb3\u0ec0\u0e99\u0eb5\u0e94 \u0eab\u0ebc\u0eb7 \u0ec0\u0edd\u0eb7\u0ead\u0e87 \u0eaa\u0ec8\u0ea7\u0e99\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0ec1\u0e81\u0ec9\u0ea7\u201d \u0edd\u0eb2\u0e8d\u0ec0\u0e96\u0eb4\u0e87\u0ec1\u0e81\u0ec9\u0ea7\u0e9b\u0eb0\u0ec0\u0eaa\u0eb5\u0e94 \u0eab\u0ebc\u0eb7 \u0ec4\u0e9e\u0ea5\u0eb4\u0e99\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0eaa\u0eb5\u0eaa\u0eb1\u0e99\u0eaa\u0ea7\u0e8d\u0e87\u0eb2\u0ea1\u0e9e\u0ebb\u0e9a\u0ec0\u0eab\u0eb1\u0e99\u0ec4\u0e94\u0ec9\u0e95\u0eb2\u0ea1\u0ec1\u0e84\u0ea1\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2\u0e82\u0ead\u0e87 \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0e8a\u0eb2\u0ea7\u0e9a\u0ec9\u0eb2\u0e99\u0e9e\u0eb2\u0e81\u0eb1\u0e99\u0e99\u0eb4\u0e8d\u0ebb\u0ea1\u0ec4\u0e9b\u0eae\u0ec8\u0ead\u0e99\u0ec0\u0ead\u0ebb\u0eb2, \u0e8d\u0ec9\u0ead\u0e99\u0ec0\u0e9b\u0eb1\u0e99\u0ec1\u0e82\u0ea7\u0e87\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0ec1\u0eae\u0ec8\u0ec1\u0e81\u0ec9\u0ea7\u0e9b\u0eb0\u0ec0\u0eaa\u0eb5\u0e94\u0eab\u0ebc\u0eb2\u0e8d\u0e88\u0eb6\u0ec8\u0e87\u0ec4\u0e94\u0ec9\u0e8a\u0eb7\u0ec8\u0ea7\u0ec8\u0eb2 \u201c\u0ec1\u0e82\u0ea7\u0e87\u0e9a\u0ecd\u0ec8\u0ec1\u0e81\u0ec9\u0ea7\u201d \u0e8a\u0eb7\u0ec8\u0e99\u0eb5\u0ec9\u0e96\u0eb7\u0e81\u0ec3\u0e8a\u0ec9\u0e95\u0eb1\u0ec9\u0e87\u0ec1\u0e95\u0ec8 \u0e9b\u0eb5 \u0e84.\u0eaa 1983 \u0ec0\u0e9b\u0eb1\u0e99\u0e95\u0ebb\u0ec9\u0e99\u0ea1\u0eb2.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><b>5. \u0eab\u0ebc\u0ea7\u0e87\u0e99<\/b><span class=\"s1\"><b>\u0ec9<\/b><\/span><b>\u0eb3\u0e97\u0eb2<\/b><\/p>\n<p class=\"p2\">\u0e84\u0ecd\u0eb2\u0ea7\u0ec8\u0eb2 \u201c\u0eab\u0ebc\u0ea7\u0e87\u201d \u0edd\u0eb2\u0e8d\u0ec0\u0e96\u0eb4\u0e87 \u201c\u0ec3\u0eab\u0e8d\u0ec8\u201d \u0ec3\u0e99\u0e9e\u0eb2\u0eaa\u0eb2\u0ea5\u0eb2\u0ea7 \u0ec3\u0e99\u0e97\u0eb5\u0ec8\u0e99\u0eb5\u0ead\u0eb2\u0e94\u0edd\u0eb2\u0e8d\u0ec0\u0e96\u0eb4\u0e87\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ec3\u0eab\u0e8d\u0ec8, \u0eaa\u0ec8\u0ea7\u0e99\u0e99\u0ecd\u0ec9\u0eb2\u0e97\u0eb2 \u0ec1\u0ea1\u0ec8\u0e99\u0edd\u0eb2\u0e8d\u0ec0\u0e96\u0eb4\u0e87\u0e8a\u0eb7\u0ec8\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2\u0eaa\u0eb2\u0e8d\u0eaa\u0eb3\u0e84\u0eb1\u0e99\u0e97\u0eb5\u0ec8\u0ec4\u0eab\u0ebc\u0e9c\u0ec8\u0eb2\u0e99\u0e95\u0ebb\u0ea7\u0ec0\u0ea1\u0eb7\u0ead\u0e87 \u0ea5\u0ea7\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0ec1\u0ea5\u0ec9\u0ea7\u0ec1\u0e9b\u0ec4\u0e94\u0ec9\u0ea7\u0ec8\u0eb2 \u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ec3\u0eab\u0e8d\u0ec8\u0e82\u0ead\u0e87\u0e99\u0ecd\u0ec9\u0eb2\u0e97\u0eb2 \u0eab\u0ebc\u0eb7 \u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ec3\u0eab\u0e8d\u0ec8\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0e99\u0ecd\u0ec9\u0eb2\u0e97\u0eb2\u0ec4\u0eab\u0ebc\u0e9c\u0ec8\u0eb2\u0e99, \u0eaa\u0ec8\u0ea7\u0e99\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0e99\u0ecd\u0ec9\u0eb2\u0e97\u0eb2\u201d \u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u201c\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2\u0ec3\u0eab\u0e8d\u0ec8\u0eaa\u0eb5\u0e82\u0ebd\u0ea7\u201d \u0e8a\u0eb7\u0ec8\u0e99\u0eb5\u0ec9\u0e96\u0eb7\u0e81\u0ec3\u0e8a\u0ec9\u0e95\u0eb1\u0ec9\u0e87\u0ec1\u0e95\u0ec8 \u0e9b\u0eb5 \u0e84.\u0eaa 1983 \u0ec0\u0e9b\u0eb1\u0e99\u0e95\u0ebb\u0ec9\u0e99\u0ea1\u0eb2.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><b>6. \u0ead<\/b><span class=\"s1\"><b>\u0eb8<\/b><\/span><b>\u0e94\u0ebb\u0ea1\u0ec4\u0e8a<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p>\n<p class=\"p2\">\u0e84\u0ecd\u0eb2\u0ea7\u0ec8\u0eb2 \u201c\u0ead\u0eb8\u0e94\u0ebb\u0ea1\u201d\u0edd\u0eb2\u0e8d\u0ec0\u0e96\u0eb4\u0e87 \u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94, \u0e9e\u0ebd\u0e87\u0e9e\u0ecd, \u0e9e\u0ebd\u0e9a\u0e9e\u0ec9\u0ead\u0ea1, \u0eaa\u0ec8\u0ea7\u0e99\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0ec4\u0e8a\u201d \u0ec1\u0ea1\u0ec8\u0e99\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e8a\u0eb7\u0ec8\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ec0\u0ead\u0e81\u0e82\u0ead\u0e87\u0ec1\u0e82\u0ea7\u0e87\u0e84\u0eb7 \u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ec4\u0e8a \u0eab\u0ebc\u0eb7 \u0ead\u0eb2\u0e94\u0e88\u0eb0\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0ec4\u0e8a\u0e8a\u0eb0\u0e99\u0eb0\u201d \u0e81\u0ecd\u0ec4\u0e94\u0ec9\u0ec0\u0e8a\u0eb1\u0ec8\u0e99\u0e81\u0eb1\u0e99 \u0ea5\u0ea7\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0ec1\u0ea5\u0ec9\u0ea7\u0ec1\u0e9b\u0ec4\u0e94\u0ec9\u0ea7\u0ec8\u0eb2 \u201c\u0ec4\u0e8a\u0e8a\u0eb0\u0e99\u0eb0\u201d \u0ead\u0eb1\u0e99\u0e84\u0ebb\u0e9a\u0e96\u0ec9\u0ea7\u0e99\u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94\u201d \u0e8a\u0eb7\u0ec8\u0e99\u0eb5\u0ec9\u0ec1\u0ea1\u0ec8\u0e99\u0e96\u0eb7\u0e81\u0e99\u0eb3\u0ec3\u0e8a\u0ec9\u0ea1\u0eb2\u0e95\u0eb1\u0ec9\u0e87\u0ec1\u0e95\u0ec8\u0e9b\u0eb5 \u0e84.\u0eaa 1969 \u0ec0\u0e9b\u0eb1\u0e99\u0e95\u0ebb\u0ec9\u0e99\u0ea1\u0eb2.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><b>7. \u0eab\u0ebb\u0ea7\u0e9e\u0eb1\u0e99<\/b><\/p>\n<p class=\"p2\">\u0e84\u0ecd\u0eb2\u0ea7\u0ec8\u0eb2 \u201c\u0eab\u0ebb\u0ea7\u0e9e\u0eb1\u0e99\u201d \u0e97\u0eb5\u0ec8\u0e81\u0eb2\u0e8d\u0ec0\u0e9b\u0eb1\u0e99\u0e8a\u0eb7\u0ec8\u0ec0\u0ead\u0eb5\u0ec9\u0e99\u0e82\u0ead\u0e87\u0ec1\u0e82\u0ea7\u0e87\u0eab\u0ebb\u0ea7\u0e9e\u0eb1\u0e99\u0e99\u0eb5\u0ec9, \u0ec3\u0e99\u0eaa\u0eb0\u0ec4\u0edd\u0e9a\u0eb9\u0eae\u0eb2\u0e99\u0eab\u0ebb\u0ea7\u0e9e\u0eb1\u0e99 \u0edd\u0eb2\u0e8d\u0ec0\u0e96\u0eb4\u0e87 \u0ec1\u0e82\u0ea7\u0e87 \u0eab\u0ebc\u0eb7 \u0eab\u0ebb\u0ea7\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0edc\u0eb6\u0ec8\u0e87 \u201c\u0eab\u0ebb\u0ea7\u0e9e\u0eb1\u0e99\u0e97\u0eb1\u0e87\u0eab\u0ec9\u0eb2\u0e97\u0eb1\u0e87\u0eab\u0ebb\u0e81\u201d \u0e81\u0ecd\u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u201c\u0ec1\u0e82\u0ea7\u0e87\u0e97\u0eb1\u0e87\u0eab\u0ec9\u0eb2\u0e97\u0eb1\u0e87\u0eab\u0ebb\u0e81\u201d \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0e84\u0ec9\u0eb2\u0e8d\u0e84\u0eb7\u0e81\u0eb1\u0e9a\u0e8a\u0eb2\u0ea7\u0ec4\u0e95\u0ea5\u0eb7\u0ec9\u0e97\u0eb5\u0ec8\u0ec0\u0ead\u0eb5\u0ec9\u0e99\u0eab\u0ebb\u0ea7\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e82\u0ead\u0e87\u0ec2\u0e95\u0ec0\u0ead\u0e87\u0ea7\u0ec8\u0eb2 \u0e9e\u0eb1\u0e99\u0e99\u0eb2, \u0ea1\u0eb5 12 \u0eab\u0ebb\u0ea7\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e9b\u0eb0\u0e81\u0ead\u0e9a\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0ec0\u0e9b\u0eb1\u0e99\u0ead\u0eb2\u0e99\u0eb2\u0e88\u0eb1\u0e81\u0edc\u0eb6\u0ec8\u0e87\u0e81\u0ecd\u0ec0\u0ead\u0eb5\u0ec9\u0e99\u0ea5\u0ea7\u0ea1\u0ea7\u0ec8\u0eb2 12 \u0e9e\u0eb1\u0e99\u0e99\u0eb2\u0ea5\u0eb7\u0ec9.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><b>8. \u0e9c\u0ebb\u0ec9\u0e87\u0eaa\u0eb2\u0ea5\u0eb5<\/b><span class=\"s1\"><b><span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/span><\/p>\n<p class=\"p2\">\u0e84\u0ecd\u0eb2\u0ea7\u0ec8\u0eb2 \u201c\u0e9c\u0ebb\u0ec9\u0e87\u0eaa\u0eb2\u0ea5\u0eb5\u201d \u0ec1\u0ea1\u0ec8\u0e99\u0e9c\u0ec9\u0ebd\u0e99\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0e9f\u0ead\u0e87\u0eaa\u0eb2\u0ea5\u0eb5\u201d \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0e9e\u0eb2\u0eaa\u0eb2\u0ec4\u0e95\u0ea5\u0eb7\u0ec9 \u0e82\u0ec9\u0eb2\u0e9e\u0eb0\u0ec0\u0e88\u0ebb\u0ec9\u0eb2\u0e8d\u0eb1\u0e87\u0e9a\u0ecd\u0ec8\u0eae\u0eb9\u0ec9\u0e84\u0ea7\u0eb2\u0ea1\u0edd\u0eb2\u0e8d\u0e97\u0eb5\u0ec8\u0e88\u0eb0\u0ec1\u0e88\u0ec9\u0e87, \u0ec1\u0e95\u0ec8\u0e81\u0ecd\u0ea1\u0eb5\u0e9c\u0eb9\u0ec9\u0e95\u0eb4\u0e94\u0e95\u0eb2\u0ea1\u0ec1\u0e9f\u0e99\u0ec0\u0e9e\u0e88\u0ecc\u0e9a\u0eb2\u0e87\u0e97\u0ec8\u0eb2\u0e99\u0e84\u0ead\u0ea1\u0ec0\u0ea1\u0eb1\u0ec9\u0e99\u0ec3\u0eab\u0ec9\u0e84\u0eb3\u0e95\u0ead\u0e9a\u0ea1\u0eb2\u0ea7\u0ec8\u0eb2 \u201c\u0e9c\u0ebb\u0ec9\u0e87\u201d \u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u0e84\u0ea7\u0eb2\u0ea1\u0e87\u0eb2\u0ea1, \u0eaa\u0ec8\u0ea7\u0e99\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0eaa\u0eb2\u0ea5\u0eb5\u201d \u0edd\u0eb2\u0e8d\u0ec0\u0e96\u0eb4\u0e87\u0e8a\u0eb7\u0ec8\u0ec2\u0e95\u0e9a\u0eb8\u0e81\u0e84\u0ebb\u0e99\u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0e9c\u0eb9\u0ec9\u0e99\u0eb3\u0e9e\u0eb2\u0ea1\u0eb2\u0e95\u0eb1\u0ec9\u0e87\u0e96\u0eb4\u0ec8\u0e99\u0e96\u0eb2\u0e99\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0ec1\u0eab\u0ec8\u0e87\u0e99\u0eb5\u0ec9.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14443\" src=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xaysomboun-1-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xaysomboun-1-scaled.jpg 2560w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xaysomboun-1-300x200.jpg 300w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xaysomboun-1-1024x683.jpg 1024w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xaysomboun-1-768x512.jpg 768w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xaysomboun-1-1536x1024.jpg 1536w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xaysomboun-1-2048x1365.jpg 2048w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xaysomboun-1-630x420.jpg 630w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xaysomboun-1-150x100.jpg 150w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xaysomboun-1-696x464.jpg 696w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xaysomboun-1-1068x712.jpg 1068w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xaysomboun-1-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p class=\"p1\"><b>9. \u0ec4\u0e8a\u0eaa\u0ebb\u0ea1\u0e9a\u0eb9\u0e99<\/b><\/p>\n<p class=\"p2\"><span class=\"Apple-converted-space\">\u00a0<\/span>\u0e84\u0ecd\u0eb2\u0ea7\u0ec8\u0eb2 \u201c\u0ec4\u0e8a\u201d \u0ea1\u0eb2\u0e88\u0eb2\u0e81 \u0ec4\u0e8a\u0e8a\u0eb0\u0e99\u0eb0, \u0eaa\u0ec8\u0ea7\u0e99\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0eaa\u0ebb\u0ea1\u0e9a\u0eb9\u0e99\u201d \u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u0ead\u0eb8\u0e94\u0ebb\u0ea1\u0eae\u0eb1\u0ec8\u0e87\u0ea1\u0eb5, \u0e84\u0ebb\u0e9a\u0e96\u0ec9\u0ea7\u0e99, \u0e84\u0eb8\u0e99\u0ea5\u0eb1\u0e81\u0eaa\u0eb0\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0e9a\u0ecd\u0ec8\u0ea1\u0eb5\u0eaa\u0eb4\u0ec8\u0e87\u0ec3\u0e94\u0e82\u0eb2\u0e94\u0e95\u0ebb\u0e81\u0e9a\u0ebb\u0e81\u0e9c\u0ec8\u0ead\u0e87 \u0ea5\u0ea7\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0ec1\u0ea5\u0ec9\u0ea7\u0e81\u0ecd\u0ec8\u0ec1\u0e9b\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0e94\u0ec9\u0ea7\u0ec8\u0eb2 \u201c\u0ec4\u0e8a\u0e8a\u0eb0\u0e99\u0eb0\u0ead\u0eb1\u0e99\u0e84\u0ebb\u0e9a\u0e96\u0ec9\u0ea7\u0e99\u0eaa\u0ebb\u0ea1\u0e9a\u0eb9\u0e99\u201d (\u0ea7\u0eb1\u0e94\u0e88\u0eb0\u0e99\u0eb2\u0e99\u0eb8\u0e81\u0ebb\u0ea1 \u0eaa\u0eb0\u0e9a\u0eb1\u0e9a\u0ea1\u0eb0\u0eab\u0eb2\u0eaa\u0eb4\u0ea5\u0eb2 \u0e9e.\u0eaa 2549) \u0e8a\u0eb7\u0ec8\u0e99\u0eb5\u0ec9\u0ec1\u0ea1\u0ec8\u0e99\u0e96\u0eb7\u0e81\u0e99\u0eb3\u0ec3\u0e8a\u0ec9\u0ea2\u0ec8\u0eb2\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0e97\u0eb2\u0e87\u0e81\u0eb2\u0e99\u0ec3\u0e99\u0e96\u0eb2\u0e99\u0eb0\u0ec1\u0e82\u0ea7\u0e87\u0e97\u0eb5 18 \u0ea1\u0eb2\u0e95\u0eb1\u0ec9\u0e87\u0ec1\u0e95\u0ec8 \u0e9b\u0eb5 \u0e84.\u0eaa 2013.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><b>10-11. \u0ec1\u0e82\u0ea7\u0e87\u0ea7\u0ebd\u0e87\u0e88\u0eb1\u0e99 \u0ec1\u0ea5\u0eb0 \u0e99\u0eb0\u0e84\u0ead\u0e99\u0eab\u0ebc\u0ea7\u0e87\u0ea7\u0ebd\u0e87\u0e88\u0eb1\u0e99<\/b><\/p>\n<p class=\"p2\">\u201c\u0ea7\u0ebd\u0e87\u201d \u0ec3\u0e99\u0e9e\u0eb2\u0eaa\u0eb2\u0ea5\u0eb2\u0ea7\u0edd\u0eb2\u0e8d\u0ec0\u0e96\u0eb4\u0e87\u0ec0\u0ea1\u0eb7\u0ead\u0e87, \u0eaa\u0ec8\u0ea7\u0e99\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0e88\u0eb1\u0e99\u201d \u0ec3\u0e99\u0e97\u0eb5\u0ec8\u0e99\u0eb5\u0ec9\u0ea1\u0eb2\u0ea1\u0eb9\u0e99\u0ec0\u0eab\u0e94\u0e97\u0eb5\u0ec8 1). \u0e88\u0eb2\u0e81\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0e88\u0eb1\u0e99\u0e97\u0e99\u0ecc\u201d<span class=\"Apple-converted-space\">\u00a0 <\/span>\u0ec3\u0e99\u0e9e\u0eb2\u0eaa\u0eb2\u0e9b\u0eb2\u0ea5\u0eb5-\u0eaa\u0eb1\u0e99\u0eaa\u0eb0\u0e81\u0eb4\u0e94 \u0e97\u0eb5\u0ec8\u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u0ec4\u0ea1\u0ec9\u0e88\u0eb1\u0e99\u0eab\u0ead\u0ea1. \u0ea1\u0eb9\u0e99\u0ec0\u0eab\u0e94\u0e97\u0eb5 2). \u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e8a\u0eb7\u0ec8\u0e82\u0ead\u0e87 \u201c\u0e97\u0ec9\u0eb2\u0ea7\u0e9a\u0eb9\u0ea5\u0eb5\u0e88\u0eb1\u0e99\u201d \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0ec0\u0e88\u0ebb\u0ec9\u0eb2\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ea7\u0ebd\u0e87\u0e88\u0eb1\u0e99\u0e84\u0ebb\u0e99\u0e97\u0eb3\u0ead\u0eb4\u0e94\u0e95\u0eb2\u0ea1\u0e99\u0eb4\u0e97\u0eb2\u0e99\u0ead\u0eb8\u0ea3\u0eb1\u0e87\u0e84\u0eb0\u0e97\u0eb2\u0e94, \u0ec1\u0e9b\u0e84\u0ea7\u0eb2\u0ea1\u0edd\u0eb2\u0e8d\u0ec4\u0e94\u0ec9\u0ec0\u0e9b\u0eb1\u0e99\u0eaa\u0ead\u0e87\u0ea2\u0ec8\u0eb2\u0e87\u0e84\u0eb7: \u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ec1\u0eab\u0ec8\u0e87\u0ec4\u0ea1\u0ec9\u0e88\u0eb1\u0e99\u0eab\u0ead\u0ea1 \u0eab\u0ebc\u0eb7 \u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e82\u0ead\u0e87 \u0e97\u0ec9\u0eb2\u0ea7\u0e9a\u0eb9\u0ea5\u0eb5\u0e88\u0eb1\u0e99.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><b>12. \u0eaa\u0eb0\u0eab\u0ea7\u0eb1\u0e99\u0e99\u0eb0\u0ec0\u0e82\u0e94<\/b><\/p>\n<p class=\"p2\">\u0e8a\u0eb7\u0ec8\u0e82\u0ead\u0e87 \u0ec1\u0e82\u0ea7\u0e87\u0eaa\u0eb0\u0eab\u0ea7\u0eb1\u0e99\u0e99\u0eb0\u0ec0\u0e82\u0e94 \u0ec1\u0ea1\u0ec8\u0e99\u0ea1\u0eb5\u0ea1\u0eb9\u0e99\u0ec0\u0eab\u0e94\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e8a\u0eb7\u0ec8\u0e82\u0ead\u0e87 \u201c\u0e9a\u0ec9\u0eb2\u0e99\u0e99\u0eb2\u0e84\u0eb3\u201d\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0eaa\u0eb8\u0ea7\u0eb1\u0e99\u0e99\u0eb0\u201d \u0ec0\u0e9b\u0eb1\u0e99\u0e9e\u0eb2\u0eaa\u0eb2\u0e9b\u0eb2\u0ea5\u0eb5-\u0eaa\u0eb1\u0e99\u0eaa\u0eb0\u0e81\u0eb4\u0e94 \u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u201c\u0e84\u0eb3\u201d \u0eaa\u0ec8\u0ea7\u0e99\u0e84\u0eb3\u0ea7\u0ec8\u0eb2\u201c\u0ec0\u0e82\u0e94\u201d \u0ec3\u0e99\u0e9e\u0eb2\u0eaa\u0eb2\u0e9b\u0eb2\u0ea5\u0eb5-\u0eaa\u0eb1\u0e99\u0eaa\u0eb0\u0e81\u0eb4\u0e94 \u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u201c\u0e99\u0eb2\u201d \u0eab\u0ebc\u0eb7 \u201c\u0ec4\u0eae\u0ec8\u0e99\u0eb2\u201d \u0eab\u0ebc\u0eb7 \u201c\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u201d \u0e95\u0ecd\u0ec8\u0ea1\u0eb2\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0ec3\u0eab\u0ec9\u0ec4\u0e94\u0ec9\u0e84\u0ea7\u0eb2\u0ea1\u0edd\u0eb2\u0e8d\u0eaa\u0eb9\u0e87\u0eaa\u0ebb\u0ec8\u0e87\u0e82\u0eb6\u0ec9\u0e99\u0e88\u0eb6\u0ec8\u0e87\u0e9c\u0eb1\u0e99\u0eaa\u0ebd\u0e87\u0e88\u0eb2\u0e81\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0eaa\u0eb8\u0ea7\u0eb1\u0e99\u0e99\u0eb0\u201d \u0ec3\u0eab\u0ec9\u0ec0\u0e9b\u0eb1\u0e99 \u201c\u0eaa\u0eb0\u0eab\u0ea7\u0eb1\u0e99\u0e99\u0eb0\u201d \u0ec1\u0e97\u0e99 \u0ec1\u0e9b\u0e84\u0ea7\u0eb2\u0ea1\u0edd\u0eb2\u0e8d\u0ec4\u0e94\u0ec9\u0ea7\u0ec8\u0eb2 \u0e9c\u0eb7\u0e99\u0ec1\u0e9c\u0ec8\u0e99\u0e94\u0eb4\u0e99\u0e84\u0eb3 \u0eab\u0ebc\u0eb7 \u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0eaa\u0eb0\u0eab\u0ea7\u0eb1\u0e99\u0e8a\u0eb1\u0ec9\u0e99\u0e9f\u0ec9\u0eb2, \u0e8a\u0eb7\u0ec8\u0e99\u0eb5\u0ec9\u0e96\u0eb7\u0e81\u0ec3\u0e8a\u0ec9\u0ec0\u0e9b\u0eb1\u0e99\u0e84\u0eb1\u0ec9\u0e87\u0e97\u0eb3\u0ead\u0eb4\u0e94\u0ec3\u0e99\u0e9b\u0eb5 \u0e84.\u0eaa 1895.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><b>13. \u0e84\u0eb3\u0ea1\u0ec8\u0ea7\u0e99<\/b><\/p>\n<p class=\"p2\">\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0e84\u0eb3\u0ea1\u0ec8\u0ea7\u0e99\u201d \u0ea1\u0eb5\u0ea1\u0eb9\u0e99\u0ec0\u0eab\u0e94\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e81\u0eb2\u0e99\u0eae\u0ec8\u0ead\u0e99\u0e84\u0eb3\u0e95\u0eb2\u0ea1\u0eaa\u0eb2\u0e8d\u0eab\u0ec9\u0ea7\u0e8d\u0e82\u0ead\u0e87\u0e8a\u0eb2\u0ea7\u0e9a\u0ec9\u0eb2\u0e99 \u0e9a\u0ec9\u0eb2\u0e99\u0e84\u0eb3\u0ec0\u0e81\u0eb5\u0e94, \u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e84\u0eb3\u0ea1\u0ec8\u0ea7\u0e99 (\u0e9b\u0eb1\u0e94\u0e88\u0eb8\u0e9a\u0eb1\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e84\u0eb3\u0ec0\u0e81\u0eb5\u0e94) \u0ec3\u0e99\u0ead\u0eb0\u0e94\u0eb5\u0e94, \u0e8a\u0eb7\u0ec8 \u201c\u0e84\u0eb3\u0ec0\u0e81\u0eb5\u0e94\u201d \u0ec1\u0ea1\u0ec8\u0e99\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e81\u0eb2\u0e99\u0e9e\u0ebb\u0e9a\u0ec0\u0eab\u0eb1\u0e99\u0e84\u0eb3\u0e97\u0eb5\u0ec8\u0ec0\u0e81\u0eb5\u0e94\u0e82\u0eb6\u0ec9\u0e99\u0ea1\u0eb2\u0ec0\u0ead\u0e87\u0e95\u0eb2\u0ea1\u0e97\u0eb3\u0ea1\u0eb0\u0e8a\u0eb2\u0e94\u0eaa\u0ec8\u0ea7\u0e99 \u201c\u0e84\u0eb3\u0ea1\u0ec8\u0ea7\u0e99\u201d \u0ec1\u0ea1\u0ec8\u0e99\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e81\u0eb2\u0e99\u0e97\u0eb5\u0ec8\u0e8a\u0eb2\u0ea7\u0e9a\u0ec9\u0eb2\u0e99\u0e9e\u0eb2\u0e81\u0eb1\u0e99\u0e9a\u0ec9\u0eb2\u0e87 \u0eab\u0ebc\u0eb7\u0eae\u0ec8\u0ead\u0e99\u0ec0\u0ead\u0ebb\u0eb2\u0e84\u0eb3 \u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0ec4\u0e94\u0ec9\u0e84\u0eb3\u0ec1\u0ea5\u0ec9\u0ea7\u0e81\u0ecd\u0ec8\u0e88\u0eb0\u0e9e\u0eb2\u0e81\u0eb1\u0e99\u0ea1\u0ec8\u0ea7\u0e99\u0e8a\u0eb7\u0ec8\u0e99 \u0e88\u0eb6\u0ec8\u0e87\u0e9e\u0eb2\u0e81\u0eb1\u0e99\u0ec0\u0ead\u0ebb\u0eb2\u0e84\u0ea7\u0eb2\u0ea1\u0e9b\u0eb0\u0e97\u0eb1\u0e9a\u0ec3\u0e88\u0e99\u0eb1\u0ec9\u0e99\u0ea1\u0eb2\u0e95\u0eb1\u0ec9\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0e8a\u0eb7\u0ec8\u0e9a\u0ec9\u0eb2\u0e99\u0e99\u0eb2\u0ea1\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ea7\u0ec8\u0eb2 \u201c\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e84\u0eb3\u0ea1\u0ec8\u0ea7\u0e99\u201d<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14440\" src=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Bolikhamxay-2-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Bolikhamxay-2-scaled.jpg 2560w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Bolikhamxay-2-300x200.jpg 300w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Bolikhamxay-2-1024x683.jpg 1024w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Bolikhamxay-2-768x512.jpg 768w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Bolikhamxay-2-1536x1024.jpg 1536w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Bolikhamxay-2-2048x1365.jpg 2048w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Bolikhamxay-2-630x420.jpg 630w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Bolikhamxay-2-150x100.jpg 150w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Bolikhamxay-2-696x464.jpg 696w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Bolikhamxay-2-1068x712.jpg 1068w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Bolikhamxay-2-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p class=\"p1\"><b>14. \u0e9a\u0ecd\u0ea5\u0eb4\u0e84\u0eb3\u0ec4\u0e8a<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p>\n<p class=\"p2\">\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0e9a\u0ecd\u0ea5\u0eb4\u0e84\u0eb3\u0ec4\u0e8a\u201d \u0ea1\u0eb5\u0ea1\u0eb9\u0e99\u0ec0\u0eab\u0e94\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e81\u0eb2\u0e99\u0ec0\u0ead\u0ebb\u0eb2\u0e8a\u0eb7\u0ec8\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0eaa\u0eb3\u0e84\u0eb1\u0e99\u0e9e\u0eb2\u0e8d\u0ec3\u0e99\u0ec1\u0e82\u0ea7\u0e87\u0e9a\u0ecd\u0ea5\u0eb4\u0e84\u0eb3\u0ec4\u0e8a\u0e97\u0eb5\u0ec8\u0ec1\u0e8d\u0e81\u0ec2\u0e95\u0ead\u0ead\u0e81\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0ec1\u0e82\u0ea7\u0e87\u0e84\u0eb3\u0ea1\u0ec8\u0ea7\u0e99\u0eaa\u0ead\u0e87\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ea1\u0eb2\u0e9b\u0eb0\u0eaa\u0ebb\u0ea1\u0e81\u0eb1\u0e99\u0e99\u0eb1\u0ec9\u0e99\u0e81\u0ecd\u0ec8\u0e84\u0eb7 \u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e9a\u0ecd\u0ea5\u0eb4\u0e84\u0eb1\u0e99\u0e97\u0eb2\u0e99\u0eb4\u0e84\u0ebb\u0ea1 \u0eab\u0ebc\u0eb7 \u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e9a\u0ecd\u0ea5\u0eb4\u0e84\u0eb1\u0e99 + \u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e84\u0eb3\u0ec0\u0e81\u0eb5\u0e94 \u0eaa\u0ec8\u0ea7\u0e99\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0ec4\u0e8a\u201d\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e84\u0eb3\u0ea7\u0ec8\u0eb2<span class=\"Apple-converted-space\">\u00a0 <\/span>\u201c\u0ec4\u0e8a\u0e8a\u0eb0\u0e99\u0eb0\u201d<span class=\"Apple-converted-space\">\u00a0 <\/span>\u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0e8a\u0eb7\u0ec8\u0e99\u0eb5\u0ec9\u0ec1\u0ea1\u0ec8\u0e99\u0e96\u0eb7\u0e81\u0e99\u0eb3\u0ec3\u0e8a\u0ec9\u0ea1\u0eb2\u0e95\u0eb1\u0ec9\u0e87\u0ec1\u0e95\u0ec8 \u0e9b\u0eb5 \u0e84.\u0eaa 1986 \u0ec0\u0e9b\u0eb1\u0e99\u0e95\u0ebb\u0ec9\u0e99\u0ea1\u0eb2.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14441\" src=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Champasak-2-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Champasak-2-scaled.jpg 2560w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Champasak-2-300x200.jpg 300w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Champasak-2-1024x683.jpg 1024w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Champasak-2-768x512.jpg 768w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Champasak-2-1536x1024.jpg 1536w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Champasak-2-2048x1365.jpg 2048w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Champasak-2-630x420.jpg 630w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Champasak-2-150x100.jpg 150w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Champasak-2-696x464.jpg 696w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Champasak-2-1068x712.jpg 1068w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Champasak-2-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p class=\"p1\"><b>15. \u0e88\u0eb3\u0e9b\u0eb2\u0eaa\u0eb1\u0e81<\/b><\/p>\n<p class=\"p2\">\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0e88\u0eb3\u0e9b\u0eb2\u201d \u0ec1\u0ea1\u0ec8\u0e99\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e8a\u0eb7\u0ec8\u0e82\u0ead\u0e87 \u201c\u0e94\u0ead\u0e81\u0e88\u0eb3\u0e9b\u0eb2\u201d \u0eab\u0ebc\u0eb7 \u0e8a\u0eb7\u0ec8\u0e82\u0ead\u0e87\u0e8a\u0ebb\u0e99\u0e8a\u0eb2\u0e94 \u201c\u0e88\u0eb2\u0ea1\u0e9b\u0eb2\u201d \u0eaa\u0ec8\u0ea7\u0e99\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0eaa\u0eb1\u0e81\u201d \u0ec1\u0ea1\u0ec8\u0e99\u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u201c\u0e96\u0eb2\u0e99\u0eb0\u201d \u0e9a\u0eb2\u0e87\u0e82\u0ecd\u0ec9\u0ea1\u0eb9\u0e99\u0e81\u0ecd\u0e9a\u0ead\u0e81\u0ea7\u0ec8\u0eb2: \u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0eaa\u0eb1\u0e81\u201d \u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0e9a\u0eb2\u0eaa\u0eb1\u0e81 (Bassac)\u201d \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0e8a\u0eb7\u0ec8\u0ec0\u0e81\u0ebb\u0ec8\u0eb2\u0e82\u0ead\u0e87\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e88\u0eb3\u0e9b\u0eb2\u0eaa\u0eb1\u0e81\u0ec3\u0e99\u0ead\u0eb0\u0e94\u0eb5\u0e94 \u0ea1\u0eb5\u0e97\u0eb5\u0ec8\u0ea1\u0eb2\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e8a\u0eb7\u0ec8\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2\u0eaa\u0eb3\u0e84\u0eb1\u0e99\u0eaa\u0eb2\u0e8d\u0edc\u0eb6\u0ec8\u0e87\u0e82\u0ead\u0e87\u0e8a\u0eb2\u0ea7\u0e88\u0eb2\u0ea1\u0eaa\u0eb0\u0ec4\u0edd\u0e9a\u0eb9\u0eae\u0eb2\u0e99.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><b>16. \u0eaa\u0eb2\u0ea5\u0eb0\u0ea7\u0eb1\u0e99<\/b><\/p>\n<p class=\"p2\">\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0eaa\u0eb2\u0ea5\u0eb0\u0ea7\u0eb1\u0e99\u201d \u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u201c\u0e9b\u0ec8\u0eb2\u0ec4\u0ea1\u0ec9\u0eae\u0eb1\u0e87 \u0eab\u0ebc\u0eb7 \u0e9b\u0ec8\u0eb2\u0e95\u0ebb\u0ec9\u0e99\u0eaa\u0eb0\u0ea5\u0eb0\u201d (\u0ea7\u0eb1\u0e94\u0e88\u0eb0\u0e99\u0eb2\u0e99\u0eb8\u0e81\u0ebb\u0ea1\u0ea5\u0eb2\u0ea7 \u0eaa\u0eb0\u0e9a\u0eb1\u0e9a \u0ea1\u0eb0\u0eab\u0eb2\u0eaa\u0eb4\u0ea5\u0eb2 \u0e9e.\u0eaa 2549) \u0e95\u0ebb\u0ec9\u0e99\u0eae\u0eb1\u0e87 \u0eab\u0ebc\u0eb7 \u0e95\u0ebb\u0ec9\u0e99\u0eaa\u0eb0\u0ea5\u0eb0\u0ec1\u0ea1\u0ec8\u0e99\u0ec0\u0e9b\u0eb1\u0e99\u0e95\u0ebb\u0ec9\u0e99\u0ec4\u0ea1\u0ec9\u0eaa\u0eb1\u0e81\u0eaa\u0eb4\u0e94\u0ec3\u0e99\u0eaa\u0eb2\u0eaa\u0eb0\u0e99\u0eb2\u0eae\u0eb4\u0e99\u0e94\u0eb9 \u0ec1\u0ea5\u0eb0 \u0eaa\u0eb2\u0eaa\u0eb0\u0edc\u0eb2\u0ec0\u0e8a\u0eb1\u0e99, \u0ec3\u0e99\u0e9a\u0ecd\u0ea5\u0eb4\u0ec0\u0ea7\u0e99\u0e97\u0eb5\u0ec8\u0ec0\u0e9b\u0eb1\u0e99\u0ec1\u0e82\u0ea7\u0e87\u0eaa\u0eb2\u0ea5\u0eb0\u0ea7\u0eb1\u0e99\u0ec3\u0e99\u0e9b\u0eb1\u0e94\u0e88\u0eb8\u0e9a\u0eb1\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0e96\u0eb7\u0e81\u0ec0\u0e95\u0ebb\u0ec9\u0eb2\u0ec2\u0eae\u0ea1\u0ea1\u0eb2\u0e88\u0eb2\u0e81 3 \u0ec1\u0e82\u0ea7\u0e87\u0e84\u0eb7: \u0ec1\u0e82\u0ea7\u0e87 \u0e95\u0eb2\u0ec0\u0ea7\u0eb1\u0e99\u0ead\u0ead\u0e81, \u0ec1\u0e82\u0ea7\u0e87 \u0eaa\u0eb2\u0ea5\u0eb0\u0ea7\u0eb1\u0e99 \u0ec1\u0ea5\u0eb0 \u0ec1\u0e82\u0ea7\u0e87\u0ea7\u0eb2\u0e9b\u0eb5\u0e84\u0eb3\u0e97\u0ead\u0e87 \u0ec3\u0e99\u0e9b\u0eb5 \u0e84.\u0eaa 1975.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14444\" src=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xekong-2-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xekong-2-scaled.jpg 2560w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xekong-2-300x200.jpg 300w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xekong-2-1024x683.jpg 1024w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xekong-2-768x512.jpg 768w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xekong-2-1536x1024.jpg 1536w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xekong-2-2048x1365.jpg 2048w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xekong-2-630x420.jpg 630w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xekong-2-150x100.jpg 150w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xekong-2-696x464.jpg 696w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xekong-2-1068x712.jpg 1068w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/06\/Xekong-2-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p class=\"p1\"><b>17. \u0ec0\u0e8a\u0e81\u0ead\u0e87<\/b><span class=\"s1\"><b><span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/span><\/p>\n<p class=\"p2\">\u201c\u0ec0\u0e8a\u0e81\u0ead\u0e87\u201d \u0ec1\u0ea1\u0ec8\u0e99\u0ea1\u0eb5\u0e97\u0eb5\u0ec8\u0ea1\u0eb2\u0e82\u0ead\u0e87\u0e8a\u0eb7\u0ec8\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2 \u201c\u0ec0\u0e8a\u0e81\u0ead\u0e87\u201d \u0ec2\u0e94\u0e8d\u0e97\u0eb5\u0ec8 \u201c\u0ec0\u0e8a\u201d \u0ec1\u0e9b\u0ea7\u0ec8\u0eb2\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2 \u0ec3\u0e99\u0e9e\u0eb2\u0eaa\u0eb2\u0e88\u0eb2\u0ea1, \u0eaa\u0ec8\u0ea7\u0e99\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0e81\u0ead\u0e87\u201d \u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e8a\u0eb7\u0ec8\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e94\u0ebb\u0e99\u0e95\u0eb5\u0e9e\u0eb7\u0ec9\u0e99\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ea5\u0eb2\u0ea7\u0e8a\u0eb0\u0e99\u0eb4\u0e94\u0edc\u0eb6\u0ec8\u0e87\u0e97\u0eb5\u0ec8\u0ec3\u0e8a\u0ec9\u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0e95\u0eb5, \u0ec1\u0e82\u0ea7\u0e87\u0ec0\u0e8a\u0e81\u0ead\u0e87\u0e96\u0eb7\u0e81\u0eaa\u0ec9\u0eb2\u0e87\u0e95\u0eb1\u0ec9\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0ec1\u0e82\u0ea7\u0e87\u0ea2\u0ec8\u0eb2\u0e87\u0eaa\u0ebb\u0ea1\u0e9a\u0eb9\u0e99 \u0ec3\u0e99\u0e9b\u0eb5 \u0e84.\u0eaa 1984 \u0e8d\u0ec9\u0ead\u0e99\u0e95\u0eb4\u0e94\u0e81\u0eb1\u0e9a\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2\u0ec0\u0e8a\u0e81\u0ead\u0e87\u0e88\u0eb6\u0ec8\u0e87\u0ec4\u0e94\u0ec9\u0e95\u0eb1\u0ec9\u0e87\u0e8a\u0eb7\u0ec8\u0ec1\u0e82\u0ea7\u0e87\u0e95\u0eb2\u0ea1\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2\u0ea7\u0ec8\u0eb2 \u201c\u0ec0\u0e8a\u0e81\u0ead\u0e87\u201d<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><b>18. \u0ead\u0eb1\u0e94\u0e95\u0eb0\u0e9b\u0eb7<\/b><\/p>\n<p class=\"p2\">\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0ead\u0eb1\u0e94\u0e95\u0eb0\u0e9b\u0eb7\u201d \u0e9e\u0ec9\u0ebd\u0e99\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0ead\u0eb4\u0e94\u0e81\u0eb0\u0e9a\u0eb7\u201d \u0eab\u0ebc\u0eb7 \u201c\u0ead\u0eb4\u0e94\u0e81\u0eb0\u0e9b\u0ea3\u0eb7\u201d \u0ec3\u0e99\u0e9e\u0eb2\u0eaa\u0eb2\u0e82\u0eb0\u0ec0\u0edd\u0e99 \u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0ead\u0eb4\u0e94\u201d \u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u0e82\u0eb5\u0ec9, \u0eaa\u0ec8\u0ea7\u0e99\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0e81\u0eb0\u0e9a\u0eb7\u201d \u0eab\u0ebc\u0eb7 \u0e81\u0eb0\u0e9b\u0ea3\u0eb7 \u0ec1\u0e9b\u0ea7\u0ec8\u0eb2\u0ea7\u0ec8\u0eb2 \u201c\u0e84\u0ea7\u0eb2\u0e8d\u201d \u0ea5\u0ea7\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0ec1\u0ea5\u0ec9\u0ea7\u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u201c\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0e82\u0eb5\u0ec9\u0e84\u0ea7\u0eb2\u0e8d\u0e9b\u0ec8\u0eb2\u0eab\u0ebc\u0eb2\u0e8d\u201d \u0ead\u0eb1\u0e94\u0e95\u0eb0\u0e9b\u0eb7\u0e96\u0eb7\u0e81\u0e8d\u0ebb\u0e81\u0e96\u0eb2\u0e99\u0eb0\u0e82\u0eb6\u0ec9\u0e99\u0ec3\u0eab\u0ec9\u0ec0\u0e9b\u0eb1\u0e99\u0ec1\u0e82\u0ea7\u0e87\u0ead\u0eb1\u0e94\u0e95\u0eb0\u0e9b\u0eb7\u0ec3\u0e99\u0e9b\u0eb5 \u0e84.\u0eaa 1954 \u0ec0\u0e9b\u0eb1\u0e99\u0e95\u0ebb\u0ec9\u0e99\u0ea1\u0eb2.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><em>\u0ead\u0ec8\u0eb2\u0e99\u0e9a\u0ebb\u0e94\u0ec0\u0e9e\u0eb4\u0ec8\u0ea1\u0e95\u0eb7\u0ec8\u0ea1\u0ec4\u0e94\u0ec9 \u0ec1\u0ea5\u0eb0 \u0e95\u0eb4\u0e94\u0e95\u0eb2\u0ea1\u0ec0\u0e9e\u0e88<span class=\"Apple-converted-space\">\u00a0<\/span><\/em><\/p>\n<p class=\"p1\"><em>Facebook: fb.com\/SnaeHistory<span class=\"Apple-converted-space\">\u00a0<\/span><\/em><\/p>\n<p class=\"p1\"><em>\u0e9a\u0ebb\u0e94\u0e99\u0eb5\u0ec9\u0e96\u0eb7\u0e81\u0ec0\u0e9c\u0eb5\u0e8d\u0ec1\u0e9c\u0ec8\u0e84\u0eb1\u0ec9\u0e87\u0e97\u0eb3\u0ead\u0eb4\u0e94: \u0ea5\u0eb0\u0eab\u0ea7\u0ec8\u0eb2\u0e87\u0ea7\u0eb1\u0e99\u0e97\u0eb5 7 \u0e81\u0eb8\u0ea1\u0e9e\u0eb2 &#8211; 23 \u0e81\u0eb8\u0ea1\u0e9e\u0eb2 2025<\/em><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>\u0eae\u0ea7\u0e9a\u0eae\u0ec8\u0ea7\u0ea1 \u0ec1\u0ea5\u0eb0 \u0e84\u0ebb\u0ec9\u0e99\u0e84\u0ea7\u0ec9\u0eb2\u0ec2\u0e94\u0e8d: \u0e97\u0ec9\u0eb2\u0ea7 \u0ea7\u0eb4\u0ea5\u0eb0 \u0e9e\u0eb9\u0ec8\u0e99\u0ea7\u0ebb\u0e87\u0eaa\u0eb2 \/ Sna\u00e9 History \u0eae\u0eb9\u0e9a\u0ec2\u0e94\u0e8d: \u0e9e\u0eb9\u0e99\u0e8a\u0eb1\u0e9a \u0ec0\u0e97\u0ea7\u0ebb\u0e87\u0eaa\u0eb2 &nbsp; 1. \u0ec1\u0e82\u0ea7\u0e87 \u0eab\u0ebc\u0ea7\u0e87\u0e9e\u0ea3\u0eb0\u0e9a\u0eb2\u0e87 \u0e84\u0ea7\u0eb2\u0ea1\u0edd\u0eb2\u0e8d\u0e97\u0eb2\u0e87\u0e94\u0ec9\u0eb2\u0e99\u0e84\u0eb3\u0eaa\u0eb1\u0e9a: \u201c\u0eab\u0ebc\u0ea7\u0e87\u201d \u0ec3\u0e99\u0e9e\u0eb2\u0eaa\u0eb2\u0ea5\u0eb2\u0ea7\u0edd\u0eb2\u0e8d\u0ec0\u0e96\u0eb4\u0e87 \u201c\u0ec3\u0eab\u0e8d\u0ec8\u201d \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0eab\u0e8d\u0ecd\u0ec9\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e84\u0eb3\u0ea7\u0ec8\u0eb2\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0eab\u0ebc\u0ea7\u0e87 \u0eab\u0ebc\u0eb7 \u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ec3\u0eab\u0e8d\u0ec8, \u0e9e\u0ea3\u0eb0\u0e9a\u0eb2\u0e87\u0ec1\u0ea1\u0ec8\u0e99\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e8a\u0eb7\u0ec8\u0e9e\u0ea3\u0eb0\u0e9e\u0eb8\u0e94\u0e97\u0eb0\u0eae\u0eb9\u0e9a\u0e84\u0eb9\u0ec8\u0e9a\u0ec9\u0eb2\u0e99\u0e84\u0eb9\u0ec8\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e82\u0ead\u0e87\u0ead\u0eb2\u0e99\u0eb2\u0e88\u0eb1\u0e81\u0ea5\u0ec9\u0eb2\u0e99\u0e8a\u0ec9\u0eb2\u0e87 \u0ea5\u0ea7\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0ec1\u0ea5\u0ec9\u0ea7 \u201c\u0eab\u0ebc\u0ea7\u0e87\u0e9e\u0ea3\u0eb0\u0e9a\u0eb2\u0e87\u201d \u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0eab\u0ebc\u0ea7\u0e87 \u0eab\u0ebc\u0eb7 \u201c\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ec3\u0eab\u0e8d\u0ec8\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0e9e\u0ea3\u0eb0\u0e9a\u0eb2\u0e87\u0eaa\u0eb0\u0e96\u0eb4\u0e94\u0ea2\u0eb9\u0ec8\u201d \u0e8a\u0eb7\u0ec8\u0e99\u0eb5\u0ec9\u0ec3\u0e8a\u0ec9\u0ea1\u0eb2\u0ec1\u0e95\u0ec8\u0e9b\u0eb5 \u0e84.\u0eaa 1560. &nbsp; 2. \u0ec1\u0e82\u0ea7\u0e87 \u0e8a\u0ebd\u0e87\u0e82\u0ea7\u0eb2\u0e87 \u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0e8a\u0ebd\u0e87\u201d \u0ec3\u0e99\u0e9e\u0eb2\u0eaa\u0eb2\u0ea5\u0eb2\u0ea7\u0ec1\u0ea1\u0ec8\u0e99\u0ea1\u0eb5\u0ec0\u0e84\u0ebb\u0ec9\u0eb2\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u0eaa\u0ec9\u0ebd\u0e99 \u0eab\u0ebc\u0eb7 \u0eaa\u0ebd\u0e99 \u0ec3\u0e99\u0e9e\u0eb2\u0eaa\u0eb2\u0e88\u0eb5\u0e99 \u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 \u0ec0\u0ea1\u0eb7\u0ead\u0e87 \u0eab\u0ebc\u0eb7 \u0e8a\u0eb8\u0ea1\u0e8a\u0ebb\u0e99\u0ec3\u0eab\u0e8d\u0ec8, \u0eaa\u0ec8\u0ea7\u0e99\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0e82\u0ea7\u0eb2\u0e87\u201d \u0ec3\u0e99\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0e8a\u0ebd\u0e87\u0e82\u0ea7\u0eb2\u0e87\u201d \u0ec1\u0ea1\u0ec8\u0e99\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e84\u0eb3\u0ea7\u0ec8\u0eb2 \u201c\u0e81\u0ea7\u0ec9\u0eb2\u0e87\u0e82\u0ea7\u0eb2\u0e87\u201d \u0ea5\u0ea7\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0ec1\u0ea5\u0ec9\u0ea7\u0ec1\u0e9b\u0ea7\u0ec8\u0eb2 [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":14442,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[725],"tags":[978,975,486,483,267,427,410,232,159,128,416,496,977,256,488,912,976,424,980,982,524,983,514,981,505,917,979,522,915,913,985,916,984,918,507],"class_list":["post-14430","post","type-post","status-publish","format-standard","has-post-thumbnail","category-history","tag-18-provinces","tag-attapeu","tag-bokeo","tag-bolikhamxay","tag-champasak","tag-houaphan","tag-khammouan","tag-luang-namtha","tag-luang-prabang","tag-oudomxay","tag-phongsaly","tag-salavan","tag-snae-history","tag-vientiane","tag-xayaboury","tag-xaysomboun","tag-xekong","tag-xieng-khouang","tag-980","tag-982","tag-524","tag-983","tag-514","tag-981","tag-505","tag-917","tag-979","tag-522","tag-915","tag-913","tag-985","tag-916","tag-984","tag-918","tag-507"],"_links":{"self":[{"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/posts\/14430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/comments?post=14430"}],"version-history":[{"count":5,"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/posts\/14430\/revisions"}],"predecessor-version":[{"id":14446,"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/posts\/14430\/revisions\/14446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/media\/14442"}],"wp:attachment":[{"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/media?parent=14430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/categories?post=14430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/tags?post=14430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}