{"id":17047,"date":"2025-09-03T16:55:45","date_gmt":"2025-09-03T09:55:45","guid":{"rendered":"https:\/\/champameuanglao.com\/?p=17047"},"modified":"2025-09-03T16:55:45","modified_gmt":"2025-09-03T09:55:45","slug":"fire-and-frenzy-laos-after-lent","status":"publish","type":"post","link":"https:\/\/champameuanglao.com\/la\/fire-and-frenzy-laos-after-lent\/","title":{"rendered":"\u0ec1\u0eaa\u0e87\u0ec4\u0e9f \u0e97\u0eb5\u0ec8\u0ea1\u0eb2\u0e9e\u0ec9\u0ead\u0ea1\u0e81\u0eb1\u0e9a\u0e84\u0ea7\u0eb2\u0ea1\u0e95\u0eb7\u0ec8\u0e99\u0ec0\u0e95\u0eb1\u0ec9\u0e99"},"content":{"rendered":"<p><figure id=\"attachment_17051\" aria-describedby=\"caption-attachment-17051\" style=\"width: 1280px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17051 size-full\" src=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I3300-copy-Large.jpeg\" alt=\"\" width=\"1280\" height=\"853\" srcset=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I3300-copy-Large.jpeg 1280w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I3300-copy-Large-300x200.jpeg 300w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I3300-copy-Large-1024x682.jpeg 1024w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I3300-copy-Large-768x512.jpeg 768w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I3300-copy-Large-630x420.jpeg 630w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I3300-copy-Large-150x100.jpeg 150w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I3300-copy-Large-696x464.jpeg 696w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I3300-copy-Large-1068x712.jpeg 1068w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><figcaption id=\"caption-attachment-17051\" class=\"wp-caption-text\">A fireboat takes to the Mekong<\/figcaption><\/figure><\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"p1\"><strong>\u0eaa\u0eb5\u0eaa\u0eb1\u0e99\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ea5\u0eb2\u0ea7\u0e9e\u0eb2\u0e8d\u0eab\u0ebc\u0eb1\u0e87\u0eaa\u0eb4\u0ec9\u0e99\u0eaa\u0eb8\u0e94\u0ec4\u0ea5\u0e8d\u0eb0\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e9e\u0eb1\u0e99\u0eaa\u0eb2<\/strong><\/h2>\n<p class=\"p1\">\u0e9a\u0ebb\u0e94\u0ec2\u0e94\u0e8d: \u0ec0\u0e88\u0eaa\u0eb1\u0e99 \u0ec2\u0ea3\u0ea5\u0eb1\u0e99<\/p>\n<p class=\"p1\">\u0eae\u0eb9\u0e9a\u0ec2\u0e94\u0e8d: \u0e9e\u0eb9\u0e99\u0e8a\u0eb1\u0e9a \u0ec0\u0e97\u0ea7\u0ebb\u0e87\u0eaa\u0eb2<\/p>\n<p class=\"p1\">\u0ec1\u0e9b \u0ec1\u0ea5\u0eb0 \u0eae\u0ebd\u0e9a\u0eae\u0ebd\u0e87\u0ec2\u0e94\u0e8d: \u0ec4\u0e9e\u0e9a\u0eb9\u0e99 \u0e97\u0eb0\u0e99\u0eb0\u0e9a\u0ebb\u0ea7\u0eaa\u0eb5<\/p>\n<p class=\"p1\">\u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0eae\u0ead\u0e94\u0e8a\u0ec8\u0ea7\u0e87\u0ec0\u0ea7\u0ea5\u0eb2\u0edc\u0eb6\u0ec8\u0e87, \u0e82\u0eb0\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0e87\u0eb2\u0e99\u0e9a\u0eb8\u0e99\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e9e\u0eb1\u0e99\u0eaa\u0eb2\u0e81\u0ecd\u0eb2\u0ea5\u0eb1\u0e87\u0e88\u0eb0\u0eaa\u0eb4\u0ec9\u0e99\u0eaa\u0eb8\u0e94\u0ea5\u0ebb\u0e87\u0ec3\u0e99\u0e8a\u0ec8\u0ea7\u0e87\u0ec0\u0e94\u0eb7\u0ead\u0e99\u0e95\u0eb8\u0ea5\u0eb2\u0e82\u0ead\u0e87\u0e97\u0eb8\u0e81\u0ec6\u0e9b\u0eb5 \u0ec1\u0ea5\u0eb0 \u0e9b\u0eb0\u0e8a\u0eb2\u0e8a\u0ebb\u0e99\u0e84\u0ebb\u0e99\u0ea5\u0eb2\u0ea7\u0e81\u0ecd\u0e9b\u0eb2\u0e81\u0ebb\u0e94\u0ea7\u0ec8\u0eb2\u0eae\u0eb9\u0ec9\u0eaa\u0eb6\u0e81\u0ec2\u0ea5\u0ec8\u0e87\u0ead\u0ebb\u0e81\u0ec2\u0ea5\u0ec8\u0e87\u0ec3\u0e88\u0eab\u0ebc\u0eb2\u0e8d\u0e82\u0eb6\u0ec9\u0e99. \u0eaa\u0eb2\u0e8d\u0e9d\u0ebb\u0e99\u0ec4\u0e94\u0ec9\u0e9e\u0eb1\u0e94\u0e9e\u0eb2\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2\u0e82\u0ead\u0e87\u0ec3\u0eab\u0ec9\u0ead\u0eb1\u0ec8\u0e87\u0ea5\u0ebb\u0ec9\u0e99\u0e88\u0ebb\u0ea1\u0ec0\u0e95\u0eb1\u0ea1\u0e9d\u0eb1\u0ec8\u0e87\u0e97\u0eb1\u0e87\u0eaa\u0ead\u0e87\u0e9f\u0eb2\u0e81, \u0e82\u0eb0\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0ec0\u0ea5\u0eb5\u0ec8\u0ea1\u0eae\u0ec9\u0ead\u0e99\u0e82\u0eb6\u0ec9\u0e99 \u0eaa\u0ebb\u0ec8\u0e87\u0ec1\u0eaa\u0e87\u0eaa\u0eb5\u0e97\u0ead\u0e87\u0e97\u0ebb\u0ec8\u0ea7\u0e97\u0eb8\u0e81\u0eaa\u0eb2\u0ea5\u0eb0\u0e97\u0eb4\u0e94, \u0ec1\u0ea5\u0eb0 \u0e97\u0ebb\u0ec8\u0ea7\u0e9b\u0eb0\u0ec0\u0e97\u0e94\u0e95\u0ec8\u0eb2\u0e87\u0e81\u0ecd\u0eab\u0ec9\u0eb2\u0e87\u0eab\u0eb2\u0e81\u0eb0\u0e81\u0ebd\u0ea1\u0e88\u0eb1\u0e94\u0e87\u0eb2\u0e99\u0e9a\u0eb8\u0e99\u0eaa\u0eb0\u0ec0\u0eab\u0ebc\u0eb5\u0ea1\u0eaa\u0eb0\u0eab\u0ebc\u0ead\u0e87\u0e81\u0eb1\u0e99\u0ea2\u0ec8\u0eb2\u0e87\u0e8d\u0eb4\u0ec8\u0e87\u0ec3\u0eab\u0e8d\u0ec8\u0e9f\u0ebb\u0e94\u0e9f\u0eb7\u0ec9\u0e99, \u0e97\u0ec8\u0eb2\u0ea1\u0e81\u0eb2\u0e87\u0ec1\u0eaa\u0e87\u0eaa\u0eb5\u0e95\u0eb2\u0ea1\u0eaa\u0eb2\u0e8d\u0e99\u0ecd\u0ec9\u0eb2, \u0ec1\u0e9b\u0ea7\u0ec4\u0e9f \u0ec1\u0ea5\u0eb0 \u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0eab\u0ebc\u0eb7\u0ec9\u0ead\u0ea1\u0ec3\u0eaa\u0eaa\u0eb1\u0e94\u0e97\u0eb2.<\/p>\n<p class=\"p2\"><span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p1\">\u0eaa\u0ecd\u0eb2\u0ea5\u0eb1\u0e9a\u0ea1\u0eb7\u0ec9\u0e97\u0eb5\u0ec8\u0ec0\u0e9b\u0eb1\u0e99\u0eaa\u0eb5\u0ea5\u0eb4\u0ea1\u0eb8\u0e87\u0e84\u0eb8\u0e99\u0e94\u0ebd\u0ea7\u0e81\u0eb1\u0e99\u0e82\u0ead\u0e87\u0e9b\u0eb5\u0e99\u0eb5\u0ec9 \u0ec1\u0ea1\u0ec8\u0e99\u0e81\u0ebb\u0e87\u0e81\u0eb1\u0e9a\u0ea7\u0eb1\u0e99\u0e97\u0eb5 8 \u0e95\u0eb8\u0ea5\u0eb2 \u0e9e\u0eb2\u0e8d\u0eab\u0ebc\u0eb1\u0e87\u0e81\u0eb2\u0e99\u0e9a\u0ecd\u0eb2\u0ec0\u0e9e\u0eb1\u0e99\u0e9e\u0ebd\u0e99\u0e9e\u0eb2\u0ea7\u0eb0\u0e99\u0eb2\u0ec4\u0ea5\u0e8d\u0eb0\u0eaa\u0eb2\u0ea1\u0ec0\u0e94\u0eb7\u0ead\u0e99\u0eaa\u0eb4\u0ec9\u0e99\u0eaa\u0eb8\u0e94\u0ea5\u0ebb\u0e87, \u0ec0\u0e97\u0eaa\u0eb0\u0e81\u0eb2\u0e99\u0e97\u0eb5\u0ec8\u0edc\u0ec9\u0eb2\u0eab\u0ebc\u0ebb\u0e87\u0ec4\u0eab\u0ebc\u0e82\u0ead\u0e87\u0ea5\u0eb2\u0ea7\u0e97\u0eb1\u0e87 2 \u0e87\u0eb2\u0e99\u0e81\u0ecd\u0ec0\u0ea5\u0eb5\u0ec8\u0ea1\u0e95\u0ebb\u0ec9\u0e99\u0e82\u0eb6\u0ec9\u0e99\u0e97\u0eb5\u0ec8\u0ec1\u0e84\u0ea1\u0e9d\u0eb1\u0ec8\u0e87\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2\u0e82\u0ead\u0e87 \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0eaa\u0eb2\u0e8d\u0e99\u0ecd\u0ec9\u0eb2\u0e97\u0eb5\u0ec8\u0ec3\u0eab\u0e8d\u0ec8\u0e97\u0eb5\u0ec8\u0eaa\u0eb8\u0e94\u0ec3\u0e99\u0ea5\u0eb2\u0ea7. \u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0eab\u0ea7\u0e99\u0e81\u0eb1\u0e9a\u0ea1\u0eb2\u0e97\u0eb5\u0ec8\u0ec1\u0e82\u0ea7\u0e87\u0eab\u0ebc\u0ea7\u0e87\u0e9e\u0eb0\u0e9a\u0eb2\u0e87, \u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0eab\u0ebc\u0ea7\u0e87\u0e9a\u0eb9\u0eae\u0eb2\u0e99\u0ec1\u0eab\u0ec8\u0e87\u0e99\u0eb5\u0ec9\u0ec4\u0e94\u0ec9\u0e81\u0eb2\u0e8d\u0ec0\u0e9b\u0eb1\u0e99\u0e94\u0eb4\u0e99\u0ec1\u0e94\u0e99\u0ea1\u0eb0\u0eab\u0eb1\u0e94\u0eaa\u0eb0\u0e88\u0eb1\u0e99\u0ec1\u0eab\u0ec8\u0e87\u0eae\u0eb8\u0ec8\u0e87\u0eaa\u0eb0\u0eab\u0ebc\u0ebb\u0ea7. \u0ea2\u0eb9\u0ec8\u0eab\u0ec8\u0eb2\u0e87\u0e88\u0eb2\u0e81\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0eab\u0ebc\u0ea7\u0e87\u0e9e\u0eb0\u0e9a\u0eb2\u0e87\u0ec4\u0e9b\u0e97\u0eb2\u0e87\u0e97\u0eb4\u0e94\u0ec3\u0e95\u0ec9\u0e9e\u0ebd\u0e87 40 \u0e99\u0eb2\u0e97\u0eb5\u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0ec0\u0e94\u0eb5\u0e99\u0e97\u0eb2\u0e87\u0ec2\u0e94\u0e8d\u0ec0\u0eae\u0eb7\u0ead\u0e9a\u0eb4\u0e99, \u0e81\u0ecd\u0ea1\u0eb5\u0e99\u0eb0\u0e84\u0ead\u0e99\u0eab\u0ebc\u0ea7\u0e87\u0ea7\u0ebd\u0e87\u0e88\u0eb1\u0e99\u0e97\u0eb5\u0ec8\u0e9e\u0ea7\u0ea1\u0e9f\u0ebb\u0e94\u0eaa\u0eb0\u0e99\u0eb1\u0ec8\u0e99\u0e94\u0ec9\u0ea7\u0e8d\u0eaa\u0ebd\u0e87\u0ec0\u0eae\u0eb7\u0ead\u0e8a\u0ec8\u0ea7\u0e87\u0e9b\u0eb0\u0eaa\u0eb2\u0e99\u0e81\u0eb1\u0e9a\u0eaa\u0ebd\u0e87\u0ec2\u0eae\u0ec8\u0eae\u0ec9\u0ead\u0e87\u0e82\u0ead\u0e87\u0e9a\u0eb1\u0e99\u0e94\u0eb2\u0e99\u0eb1\u0e81\u0e8a\u0ebb\u0ea1-\u0ec0\u0e8a\u0e8d\u0ea2\u0eb9\u0ec8\u0ec1\u0e84\u0ea1\u0e9d\u0eb1\u0ec8\u0e87\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2, \u0ec1\u0e95\u0ec8\u0e81\u0eb2\u0e99\u0eaa\u0eb0\u0ec0\u0eab\u0ebc\u0eb5\u0ea1\u0eaa\u0eb0\u0eab\u0ebc\u0ead\u0e87\u0e87\u0eb2\u0e99\u0e9a\u0eb8\u0e99\u0e94\u0eb1\u0ec8\u0e87\u0e81\u0ec8\u0eb2\u0ea7\u0ec3\u0e99\u0ec1\u0e95\u0ec8\u0ea5\u0eb0\u0e84\u0eb1\u0ec9\u0e87 \u0ea5\u0ec9\u0ea7\u0e99\u0ec1\u0e95\u0ec8\u0eaa\u0eb0\u0e97\u0ec9\u0ead\u0e99\u0ec3\u0eab\u0ec9\u0ec0\u0eab\u0eb1\u0e99\u0ec0\u0e96\u0eb4\u0e87\u0e88\u0eb4\u0e94\u0ea7\u0eb4\u0e99\u0e8d\u0eb2\u0e99\u0e82\u0ead\u0e87\u0e9b\u0eb0\u0e8a\u0eb2\u0e8a\u0ebb\u0e99\u0ea5\u0eb2\u0ea7\u0e97\u0eb5\u0ec8\u0eaa\u0eb0\u0ec1\u0e94\u0e87\u0ead\u0ead\u0e81\u0ec3\u0e99\u0eab\u0ebc\u0eb2\u0e8d\u0ec1\u0e87\u0ec8\u0ea1\u0eb8\u0ea1.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_17048\" aria-describedby=\"caption-attachment-17048\" style=\"width: 1280px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17048 size-full\" src=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I0069-copy-Large.jpeg\" alt=\"\" width=\"1280\" height=\"853\" srcset=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I0069-copy-Large.jpeg 1280w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I0069-copy-Large-300x200.jpeg 300w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I0069-copy-Large-1024x682.jpeg 1024w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I0069-copy-Large-768x512.jpeg 768w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I0069-copy-Large-630x420.jpeg 630w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I0069-copy-Large-150x100.jpeg 150w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I0069-copy-Large-696x464.jpeg 696w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I0069-copy-Large-1068x712.jpeg 1068w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><figcaption id=\"caption-attachment-17048\" class=\"wp-caption-text\">\u0e9e\u0eb2\u0e9a\u0e9a\u0eb1\u0e99\u0e8d\u0eb2\u0e81\u0eb2\u0e94\u0e9a\u0eb8\u0e99\u0ec4\u0eab\u0ebc\u0ec0\u0eae\u0eb7\u0ead\u0ec4\u0e9f\u0ea2\u0eb9\u0ec8\u0eab\u0ebc\u0ea7\u0e87\u0e9e\u0eb0\u0e9a\u0eb2\u0e87<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h3 class=\"p1\"><strong>\u0eab\u0ebc\u0ea7\u0e87\u0e9e\u0eb0\u0e9a\u0eb2\u0e87: \u0e9a\u0ec8\u0ead\u0e99\u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0ec1\u0eaa\u0e87\u0ec4\u0e9f\u0ea5\u0ead\u0e8d\u0ea5\u0ec8\u0ead\u0e87\u0ec0\u0e97\u0eb4\u0e87\u0edc\u0ec9\u0eb2\u0e99\u0ecd\u0ec9\u0eb2<\/strong><\/h3>\n<p class=\"p1\">\u0e9a\u0ecd\u0ec8\u0ea1\u0eb5\u0eaa\u0eb4\u0ec8\u0e87\u0ec3\u0e94\u0e97\u0eb5\u0ec8\u0e88\u0eb0\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e81\u0eb0\u0e81\u0ebd\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0e9e\u0ec9\u0ead\u0ea1\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0e95\u0ec9\u0ead\u0e99\u0eae\u0eb1\u0e9a\u0ec1\u0e82\u0e81\u0e9a\u0ec9\u0eb2\u0e99\u0ec1\u0e82\u0e81\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e97\u0eb5\u0ec8\u0ec0\u0e94\u0eb5\u0e99\u0e97\u0eb2\u0e87\u0ea1\u0eb2\u0e97\u0ec8\u0ebd\u0ea7\u0e8a\u0ebb\u0ea1\u0eab\u0ebc\u0ea7\u0e87\u0e9e\u0eb0\u0e9a\u0eb2\u0e87\u0ec4\u0e94\u0ec9\u0ea2\u0ec8\u0eb2\u0e87\u0eaa\u0ebb\u0ea1\u0e9a\u0eb9\u0e99\u0ec1\u0e9a\u0e9a\u0e97\u0ebd\u0ea1\u0e97\u0eb1\u0e99\u0ec0\u0e97\u0ebb\u0ec8\u0eb2\u0e87\u0eb2\u0e99\u0e9a\u0eb8\u0e99\u0ec4\u0eab\u0ebc\u0ec0\u0eae\u0eb7\u0ead\u0ec4\u0e9f. \u0ec3\u0e99\u0e82\u0eb0\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0e94\u0ea7\u0e87\u0e95\u0eb2\u0ec0\u0ea7\u0eb1\u0e99\u0e9e\u0ea7\u0ea1\u0ea5\u0eb2\u0ea5\u0eb1\u0e9a\u0eaa\u0eb9\u0ec8\u0e82\u0ead\u0e9a\u0e9f\u0ec9\u0eb2\u0e9f\u0eb2\u0e81\u0edc\u0ec8\u0ea7\u0e8d\u0e9e\u0eb9\u0eaa\u0eb9\u0e87\u0ec0\u0e94\u0eb1\u0ec8\u0e99\u0ec0\u0edc\u0eb7\u0ead\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ea1\u0ecd\u0ea5\u0eb0\u0e94\u0ebb\u0e81\u0ec2\u0ea5\u0e81\u0e82\u0ead\u0e87\u0ead\u0ebb\u0e87\u0e81\u0eb2\u0e99 UNESCO \u0ec1\u0eab\u0ec8\u0e87\u0e99\u0eb5\u0ec9, \u0e81\u0ecd\u0ea1\u0eb5\u0e9a\u0eb2\u0e87\u0eaa\u0eb4\u0ec8\u0e87\u0e97\u0eb5\u0ec8\u0edc\u0ec9\u0eb2\u0ead\u0eb1\u0e94\u0eaa\u0eb0\u0e88\u0eb1\u0e99\u0ec4\u0e94\u0ec9\u0ec0\u0ea5\u0eb5\u0ec8\u0ea1\u0e9b\u0eb2\u0e81\u0ebb\u0e94\u0e95\u0ebb\u0ea7\u0e82\u0eb6\u0ec9\u0e99. \u0e81\u0eb2\u0e99\u0e97\u0eb5\u0ec8\u0ec1\u0eaa\u0e87\u0ec4\u0e9f\u0e9f\u0ec9\u0eb2\u0e88\u0eb0\u0e84\u0ec8\u0ead\u0e8d\u0e94\u0eb1\u0e9a\u0ea1\u0ead\u0e94\u0ea5\u0ebb\u0e87\u0ec0\u0e97\u0eb7\u0ec8\u0ead\u0ea5\u0eb0\u0e94\u0ea7\u0e87\u0e99\u0eb1\u0ec9\u0e99 \u0e9a\u0ecd\u0ec8\u0ec1\u0ea1\u0ec8\u0e99\u0ec0\u0eab\u0e94\u0e81\u0eb2\u0e99\u0e9a\u0eb1\u0e87\u0ec0\u0ead\u0eb5\u0e99\u0ec1\u0e95\u0ec8\u0ea2\u0ec8\u0eb2\u0e87\u0ec3\u0e94 \u0ec1\u0e95\u0ec8\u0ec0\u0e9b\u0eb1\u0e99\u0e8d\u0ec9\u0ead\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0e95\u0eb1\u0ec9\u0e87\u0ec3\u0e88\u0e82\u0ead\u0e87\u0e9c\u0eb9\u0ec9\u0e84\u0ebb\u0e99\u0ec3\u0e99\u0e97\u0eb5\u0ec8\u0e99\u0eb1\u0ec9\u0e99\u0ec0\u0ead\u0e87. \u0ea7\u0eb1\u0e94\u0ea7\u0eb2\u0ead\u0eb2\u0eae\u0eb2\u0ea1\u0e97\u0eb8\u0e81\u0ec6\u0ec1\u0eab\u0ec8\u0e87, \u0e95\u0eb0\u0eab\u0ebc\u0ead\u0e94\u0eae\u0ead\u0e94\u0eae\u0ec9\u0eb2\u0e99\u0e84\u0ec9\u0eb2, \u0e9a\u0ec9\u0eb2\u0e99\u0ec0\u0eae\u0eb7\u0ead\u0e99\u0e97\u0eb8\u0e81\u0eab\u0ebc\u0eb1\u0e87\u0e95\u0ec8\u0eb2\u0e87\u0e81\u0ecd\u0e9e\u0eb2\u0e81\u0eb1\u0e99\u0e9b\u0eb0\u0e96\u0eb4\u0ec9\u0ea1\u0ec1\u0eaa\u0e87\u0ead\u0eb1\u0e99\u0ec0\u0e88\u0eb5\u0e94\u0e88\u0ec9\u0eb2\u0e82\u0ead\u0e87\u0e94\u0ea7\u0e87\u0ec4\u0e9f\u0eaa\u0eb0\u0ec4\u0edd\u0ec3\u0edd\u0ec8 \u0e9e\u0ec9\u0ead\u0ea1\u0e81\u0ec9\u0eb2\u0ea7\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0eaa\u0eb9\u0ec8\u0ec1\u0eaa\u0e87\u0e97\u0ebd\u0e99 \u0ec1\u0ea5\u0eb0 \u0ec2\u0e84\u0ea1\u0ec4\u0e9f\u0ec0\u0e88\u0ec9\u0e8d \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0ec1\u0e9c\u0ec8\u0ec1\u0eaa\u0e87\u0e9e\u0ecd\u0eae\u0eb4\u0e9a\u0eae\u0eb5\u0ec8. \u0e88\u0eb2\u0e81\u0e99\u0eb1\u0ec9\u0e99, \u0e95\u0ebb\u0ea7\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e97\u0eb1\u0e87\u0edd\u0ebb\u0e94\u0e81\u0ecd\u0e81\u0eb1\u0e9a\u0e81\u0eb2\u0e8d\u0ea1\u0eb2\u0ec0\u0e9b\u0eb1\u0e99\u0e9c\u0ebb\u0e99\u0e87\u0eb2\u0e99\u0eaa\u0eb4\u0ea5\u0eb0\u0e9b\u0eb0\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0e8a\u0eb5\u0ea7\u0eb4\u0e94\u0e8a\u0eb5\u0ea7\u0eb2 \u0ec1\u0ea5\u0eb0 \u0ea1\u0eb5\u0ea5\u0ebb\u0ea1\u0eab\u0eb1\u0e99\u0ec3\u0e88.<\/p>\n<p class=\"p2\"><span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p1\">\u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0ec0\u0ea5\u0eb5\u0ec8\u0ea1\u0e9e\u0eb4\u0e97\u0eb5\u0e82\u0eb0\u0e9a\u0ea7\u0e99\u0ec1\u0eab\u0ec8\u0ec0\u0eae\u0eb7\u0ead\u0ec4\u0e9f, \u0e9b\u0eb0\u0e8a\u0eb2\u0e8a\u0ebb\u0e99\u0e88\u0eb2\u0e81\u0e9a\u0ec9\u0eb2\u0e99\u0e95\u0ec8\u0eb2\u0e87\u0ec6\u0e88\u0eb0\u0e99\u0ecd\u0eb2\u0ec0\u0ead\u0ebb\u0eb2\u0ec0\u0eae\u0eb7\u0ead\u0ec4\u0e9f\u0e97\u0eb5\u0ec8\u0e9e\u0ea7\u0e81\u0e95\u0ebb\u0e99\u0e9b\u0eb0\u0e94\u0eb4\u0e94\u0e82\u0eb6\u0ec9\u0e99\u0e94\u0ec9\u0ea7\u0e8d\u0e84\u0ea7\u0eb2\u0ea1\u0e9e\u0eb2\u0e81\u0e9e\u0eb9\u0ea1\u0ec3\u0e88 \u0e97\u0eb1\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0e97\u0eb5\u0ec8\u0eae\u0eb1\u0e81\u0eab\u0ead\u0ea1\u0e9b\u0ebd\u0e9a\u0eaa\u0eb0\u0ec0\u0edd\u0eb7\u0ead\u0e99\u0ea5\u0eb9\u0e81\u0eab\u0ebc\u0eb2\u0e99\u0e84\u0eb5\u0e87\u0ec6\u0e82\u0ead\u0e87\u0e9e\u0ea7\u0e81\u0e95\u0ebb\u0e99\u0e99\u0eb1\u0ec9\u0e99\u0ea1\u0eb2\u0ead\u0ea7\u0e94\u0eae\u0eb9\u0e9a\u0ec2\u0eaa\u0ea1\u0ec3\u0eab\u0ec9\u0e9b\u0ea7\u0e87\u0e8a\u0ebb\u0e99\u0ec0\u0e8a\u0eb5\u0e8d\u0e8a\u0ebb\u0ea1. \u0ec0\u0eae\u0eb7\u0ead\u0ec0\u0eab\u0ebc\u0ebb\u0ec8\u0eb2\u0e99\u0eb5\u0ec9\u0e9a\u0ecd\u0ec8\u0ec4\u0e94\u0ec9\u0ec0\u0e9b\u0eb1\u0e99\u0e9e\u0ebd\u0e87\u0ec0\u0eae\u0eb7\u0ead\u0e97\u0ecd\u0eb2\u0ea1\u0eb0\u0e94\u0eb2\u0e97\u0ebb\u0ec8\u0ea7\u0ec4\u0e9b, \u0ec1\u0e95\u0ec8\u0ec0\u0e9b\u0eb1\u0e99\u0e9c\u0ebb\u0e99\u0e87\u0eb2\u0e99\u0ead\u0eb1\u0e99\u0ec0\u0e94\u0eb1\u0ec8\u0e99\u0eaa\u0eb0\u0eab\u0e87\u0ec8\u0eb2 \u0e97\u0eb5\u0ec8\u0eaa\u0eb0\u0ec1\u0e94\u0e87\u0ec3\u0eab\u0ec9\u0ec0\u0eab\u0eb1\u0e99\u0ec0\u0e96\u0eb4\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0eab\u0ebc\u0eb7\u0ec9\u0ead\u0ea1\u0ec3\u0eaa\u0eaa\u0eb1\u0e94\u0e97\u0eb2\u0e82\u0ead\u0e87\u0e9e\u0ecd\u0ec8\u0ec1\u0ea1\u0ec8\u0e9b\u0eb0\u0e8a\u0eb2\u0e8a\u0ebb\u0e99\u0ea5\u0eb2\u0ea7, \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0ead\u0ebb\u0e87\u0e9b\u0eb0\u0e81\u0ead\u0e9a\u0e82\u0ead\u0e87\u0ec0\u0eae\u0eb7\u0ead\u0e9b\u0eb0\u0ec0\u0e9e\u0e94\u0e94\u0eb1\u0ec8\u0e87\u0e81\u0ec8\u0eb2\u0ea7\u0ec1\u0ea1\u0ec8\u0e99: \u0ec2\u0e84\u0e87\u0ec4\u0ea1\u0ec9\u0ec3\u0e9c\u0ec8\u0e97\u0eb5\u0ec8\u0eab\u0ecd\u0ec8\u0eab\u0eb8\u0ec9\u0ea1\u0e94\u0ec9\u0ea7\u0e8d\u0ec0\u0e88\u0ec9\u0e8d\u0eaa\u0eb5, \u0e97\u0eb1\u0e87\u0e9b\u0eb0\u0e94\u0eb1\u0e9a\u0e9b\u0eb0\u0e94\u0eb2\u0e94\u0ec9\u0ea7\u0e8d\u0eae\u0eb9\u0e9a\u0eaa\u0eb1\u0e94 12 \u0ea5\u0eb2\u0eaa\u0eb5 \u0e84\u0ec9\u0eb2\u0e8d\u0e81\u0eb1\u0e9a\u0ea7\u0ec8\u0eb2\u0e88\u0eb0\u0ec0\u0e9b\u0eb1\u0ec8\u0e87\u0ec1\u0eaa\u0e87\u0ead\u0ead\u0e81\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e82\u0ec9\u0eb2\u0e87\u0ec3\u0e99. \u0ec0\u0eae\u0eb7\u0ead\u0e9a\u0eb2\u0e87\u0ea5\u0ecd\u0eb2\u0e81\u0ecd\u0ea1\u0eb5\u0ea5\u0eb1\u0e81\u0eaa\u0eb0\u0e99\u0eb0\u0e97\u0ecd\u0eb2\u0ea1\u0eb0\u0e94\u0eb2\u0ec1\u0e95\u0ec8\u0ec1\u0e9d\u0e87\u0e8a\u0ec9\u0ead\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0e87\u0ebb\u0e94\u0e87\u0eb2\u0ea1, \u0e82\u0eb0\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0ec0\u0eae\u0eb7\u0ead\u0e9a\u0eb2\u0e87\u0ea5\u0ecd\u0eb2\u0e81\u0ecd\u0ec0\u0e9b\u0eb1\u0e99\u0e9c\u0ebb\u0e99\u0e87\u0eb2\u0e99\u0e8a\u0eb1\u0ec9\u0e99\u0ec0\u0ead\u0e81\u0ec3\u0e99\u0eae\u0eb9\u0e9a\u0ec1\u0e9a\u0e9a\u0eaa\u0eb4\u0ea5\u0eb0\u0e9b\u0eb0\u0e9a\u0eb2\u0ec2\u0ea3\u0e81 (baroque) \u0ec2\u0e94\u0e8d\u0ec3\u0e8a\u0ec9\u0ec0\u0ea7\u0ea5\u0eb2\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0e9b\u0eb0\u0e94\u0eb4\u0e94\u0eaa\u0ec9\u0eb2\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0eab\u0ebc\u0eb2\u0e8d\u0ec0\u0e94\u0eb7\u0ead\u0e99.<\/p>\n<p class=\"p2\"><span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p1\">\u0e82\u0eb0\u0e9a\u0ea7\u0e99\u0ec1\u0eab\u0ec8\u0ec0\u0eae\u0eb7\u0ead\u0ec4\u0e9f \u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0ec0\u0e9a\u0eb4\u0ec8\u0e87\u0ead\u0eb5\u0e81\u0ea1\u0eb8\u0ea1\u0edc\u0eb6\u0ec8\u0e87\u0e81\u0ecd\u0e9a\u0ecd\u0ec8\u0e95\u0ec8\u0eb2\u0e87\u0eab\u0e8d\u0eb1\u0e87\u0e81\u0eb1\u0e9a\u0eaa\u0eb2\u0e81\u0eaa\u0eb0\u0ec1\u0e94\u0e87\u0ea5\u0eb0\u0e84\u0ead\u0e99\u0ec0\u0ea7\u0e97\u0eb5. \u0eaa\u0ebd\u0e87\u0e81\u0ead\u0e87\u0e81\u0eb0\u0e97\u0ebb\u0e9a\u0e81\u0eb1\u0e9a\u0eaa\u0ebd\u0e87\u0e82\u0eb1\u0e9a\u0ea5\u0ecd\u0eb2\u0e9e\u0eb7\u0ec9\u0e99\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e94\u0ec9\u0ea7\u0e8d\u0e88\u0eb1\u0e87\u0eab\u0ea7\u0eb0\u0e97\u0eb5\u0ec8\u0ea1\u0ec8\u0ea7\u0e99\u0ead\u0ead\u0e99\u0e8a\u0ead\u0e99, \u0e82\u0eb0\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0eaa\u0ebd\u0e87\u0ec0\u0e9e\u0e87\u0e9e\u0eb7\u0ec9\u0e99\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ec3\u0e99\u0ec0\u0ea7\u0ea5\u0eb2\u0ec3\u0e94\u0e81\u0ecd\u0e94\u0eb1\u0e87\u0e81\u0ec9\u0ead\u0e87\u0e81\u0eb1\u0e87\u0ea7\u0eb2\u0e99\u0ea2\u0eb9\u0ec8\u0e97\u0ebb\u0ec8\u0ea7\u0ec0\u0eaa\u0eb1\u0ec9\u0e99\u0e97\u0eb2\u0e87\u0eaa\u0eb2\u0e8d\u0e99\u0eb5\u0ec9\u0ea1\u0eb2\u0eab\u0ebc\u0eb2\u0e8d\u0eaa\u0eb0\u0e95\u0eb0\u0ea7\u0eb1\u0e94. \u0e82\u0eb0\u0e9a\u0ea7\u0e99\u0ec1\u0eab\u0ec8\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99\u0e97\u0eb5\u0ec8\u0ea2\u0ec8\u0eb2\u0e87\u0e8a\u0ec9\u0eb2\u0ec6\u0e84\u0ec9\u0eb2\u0e8d\u0e84\u0eb7\u0e81\u0eb1\u0e9a\u0ea2\u0eb9\u0ec8\u0ec3\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0e9d\u0eb1\u0e99, \u0ec2\u0e94\u0e8d\u0ec0\u0e9b\u0eb5\u0e94\u0ec2\u0ead\u0e81\u0eb2\u0e94\u0ec3\u0eab\u0ec9\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e94\u0eb7\u0ec8\u0ea1\u0e94\u0ecd\u0eb2\u0e81\u0eb1\u0e9a\u0e97\u0eb8\u0e81\u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd\u0e94\u0ec4\u0e94\u0ec9\u0ec0\u0e9b\u0eb1\u0e99\u0ea2\u0ec8\u0eb2\u0e87\u0e94\u0eb5. \u0e9a\u0eb1\u0e99\u0e94\u0eb2\u0ec0\u0e94\u0eb1\u0e81\u0e99\u0ec9\u0ead\u0e8d\u0e81\u0ecd\u0e9e\u0eb2\u0e81\u0eb1\u0e99\u0e8d\u0ec8\u0eb2\u0e87\u0e95\u0eb2\u0ea1\u0eab\u0ebc\u0eb1\u0e87\u0e82\u0eb0\u0e9a\u0ea7\u0e99\u0ec1\u0eab\u0ec8 \u0ec3\u0e99\u0ea1\u0eb7\u0e96\u0eb7\u0e94\u0ead\u0e81\u0ec4\u0ea1\u0ec9\u0ec4\u0e9f \u0e97\u0eb1\u0e87\u0eaa\u0ebb\u0ec8\u0e87\u0eaa\u0ebd\u0e87\u0eab\u0ebb\u0ea7\u0ea2\u0ead\u0e81\u0ec4\u0e8d\u0e81\u0eb1\u0e99\u0ea2\u0ec8\u0eb2\u0e87\u0ea1\u0ec8\u0ea7\u0e99\u0e8a\u0eb7\u0ec8\u0e99 \u0ec0\u0eae\u0eb1\u0e94\u0ec3\u0eab\u0ec9\u0e9e\u0eb2\u0e9a\u0e9a\u0eb1\u0e99\u0e8d\u0eb2\u0e81\u0eb2\u0e94\u0e9f\u0ebb\u0e94\u0e9f\u0eb7\u0ec9\u0e99\u0e8d\u0eb4\u0ec8\u0e87\u0e82\u0eb6\u0ec9\u0e99.<\/p>\n<p class=\"p2\"><span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p1\">\u0e9e\u0eb2\u0e9a\u0ead\u0eb1\u0e99\u0e87\u0ebb\u0e94\u0e87\u0eb2\u0ea1\u0e95\u0eb0\u0e81\u0eb2\u0e99\u0e95\u0eb2\u0e94\u0eb1\u0ec8\u0e87\u0e81\u0ec8\u0eb2\u0ea7\u0e8d\u0eb1\u0e87\u0e84\u0ebb\u0e87\u0e94\u0ecd\u0eb2\u0ec0\u0e99\u0eb5\u0e99\u0e95\u0ecd\u0ec8\u0ec4\u0e9b\u0e88\u0ebb\u0e99\u0eae\u0ead\u0e94\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2, \u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0ec0\u0eae\u0eb7\u0ead\u0ec4\u0e9f\u0ea5\u0ecd\u0eb2\u0e97\u0ecd\u0eb2\u0ead\u0eb4\u0e94\u0e96\u0eb7\u0e81\u0e9b\u0ec8\u0ead\u0e8d\u0ea5\u0ebb\u0e87\u0eaa\u0eb9\u0ec8\u0edc\u0ec9\u0eb2\u0e99\u0ecd\u0ec9\u0eb2\u0ead\u0eb1\u0e99\u0ea1\u0eb7\u0e94\u0ea1\u0eb4\u0e94\u0e82\u0ead\u0e87\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2\u0e82\u0ead\u0e87, \u0e9b\u0eb2\u0e81\u0ebb\u0e94\u0ea7\u0ec8\u0eb2\u0e8a\u0ec8\u0ea7\u0e87\u0ec0\u0ea7\u0ea5\u0eb2\u0ec4\u0e94\u0ec9\u0ea2\u0eb8\u0e94\u0e99\u0eb4\u0ec9\u0e87\u0ec4\u0e9b\u0e8a\u0ebb\u0ec8\u0ea7\u0e82\u0eb0\u0e99\u0eb0\u0edc\u0eb6\u0ec8\u0e87. \u0ec1\u0eaa\u0e87\u0ec4\u0e9f\u0ec0\u0ea5\u0eb5\u0ec8\u0ea1\u0eaa\u0eb0\u0e97\u0ec9\u0ead\u0e99\u0ead\u0ead\u0e81\u0ea1\u0eb2 \u0ec1\u0ea5\u0eb0 \u0e97\u0eb0\u0ea7\u0eb5\u0e84\u0eb9\u0e99\u0e82\u0eb6\u0ec9\u0e99\u0ec0\u0e97\u0eb4\u0e87\u0edc\u0ec9\u0eb2\u0e99\u0ecd\u0ec9\u0eb2, \u0e81\u0ecd\u0ec8\u0e81\u0ecd\u0eb2\u0ec0\u0e99\u0eb5\u0e94\u0e81\u0eb8\u0ec8\u0ea1\u0ec1\u0eaa\u0e87\u0eae\u0eb4\u0e9a\u0eae\u0eb5\u0ec8\u0e97\u0eb5\u0ec8\u0ea5\u0ead\u0e8d\u0ea5\u0ec8\u0ead\u0e87\u0e95\u0eb2\u0ea1\u0eaa\u0eb2\u0e8d\u0e99\u0ecd\u0ec9\u0eb2 \u0e9b\u0ebd\u0e9a\u0e94\u0eb1\u0ec8\u0e87\u0e94\u0ea7\u0e87\u0e94\u0eb2\u0ea7\u0e97\u0eb5\u0ec8\u0e95\u0ebb\u0e81\u0eab\u0ebc\u0ebb\u0ec8\u0e99\u0ea5\u0ebb\u0e87\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0ec0\u0e97\u0eb4\u0e87\u0e9f\u0ec9\u0eb2. \u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0ec0\u0e9d\u0ebb\u0ec9\u0eb2\u0ec0\u0e9a\u0eb4\u0ec8\u0e87\u0e9e\u0eb4\u0e97\u0eb5\u0e81\u0ecd\u0eb2\u0e9e\u0eb7\u0ec9\u0e99\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e97\u0eb5\u0ec8\u0e9e\u0ea7\u0ea1\u0ea5\u0ead\u0e8d\u0ea5\u0ec8\u0ead\u0e87\u0ea5\u0eb1\u0e81\u0eaa\u0eb0\u0e99\u0eb0\u0e99\u0eb5\u0ec9, \u0e88\u0eb0\u0e8a\u0ec8\u0ea7\u0e8d\u0ec3\u0eab\u0ec9\u0e97\u0ec8\u0eb2\u0e99\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0ec3\u0e88\u0ec0\u0e96\u0eb4\u0e87\u0ec0\u0eab\u0e94\u0e9c\u0ebb\u0e99\u0e97\u0eb5\u0ec8\u0e9b\u0eb0\u0e8a\u0eb2\u0e8a\u0ebb\u0e99\u0ea5\u0eb2\u0ea7\u0e9e\u0eb2\u0e81\u0eb1\u0e99\u0ec0\u0e8a\u0eb7\u0ec8\u0ead\u0ea7\u0ec8\u0eb2 \u0e9a\u0eb1\u0e99\u0e94\u0eb2\u0ec0\u0eae\u0eb7\u0ead\u0ec4\u0e9f\u0ec0\u0eab\u0ebc\u0ebb\u0ec8\u0eb2\u0e99\u0eb5\u0ec9\u0e88\u0eb0\u0e8a\u0ec8\u0ea7\u0e8d\u0e9b\u0eb1\u0e94\u0ec0\u0e9b\u0ebb\u0ec8\u0eb2\u0eaa\u0eb4\u0ec8\u0e87\u0e9a\u0ecd\u0ec8\u0e94\u0eb5\u0e97\u0eb1\u0e87\u0e9b\u0ea7\u0e87\u0ec3\u0eab\u0ec9\u0ec4\u0eab\u0ebc\u0edc\u0eb5\u0ec4\u0e9b\u0e81\u0eb1\u0e9a\u0eaa\u0eb2\u0e8d\u0e99\u0ecd\u0ec9\u0eb2 \u0e9e\u0ec9\u0ead\u0ea1\u0e99\u0ecd\u0eb2\u0e9e\u0eb2\u0ec1\u0e95\u0ec8\u0eaa\u0eb4\u0ec8\u0e87\u0e94\u0eb5\u0ec6, \u0ea1\u0eb5\u0eaa\u0eb5\u0ea5\u0eb4\u0ea1\u0eb8\u0e87\u0e84\u0eb8\u0e99\u0ea1\u0eb2\u0eaa\u0eb9\u0ec8\u0e9b\u0ea7\u0e87\u0e8a\u0ebb\u0e99\u0ec3\u0e99\u0e9b\u0eb5\u0e95\u0ecd\u0ec8\u0ec4\u0e9b.<\/p>\n<p class=\"p2\"><span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p1\">\u0e9e\u0eb4\u0e97\u0eb5\u0e81\u0ecd\u0eb2\u0e94\u0eb1\u0ec8\u0e87\u0e81\u0ec8\u0eb2\u0ea7\u0e9a\u0ecd\u0ec8\u0e9e\u0ebd\u0e87\u0ec1\u0e95\u0ec8\u0ec0\u0e9b\u0eb1\u0e99\u0e81\u0eb2\u0e99\u0eaa\u0eb0\u0ec1\u0e94\u0e87\u0ead\u0eb1\u0e99\u0edc\u0ec9\u0eb2\u0e95\u0eb7\u0ec8\u0e99\u0e95\u0eb2\u0e95\u0eb7\u0ec8\u0e99\u0ec3\u0e88\u0ec0\u0e97\u0ebb\u0ec8\u0eb2\u0e99\u0eb1\u0ec9\u0e99, \u0ec1\u0e95\u0ec8\u0e8d\u0eb1\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0e9e\u0eb4\u0e97\u0eb5\u0e81\u0ecd\u0eb2\u0eaa\u0eb1\u0e81\u0eaa\u0eb4\u0e94\u0e97\u0eb5\u0ec8\u0ec0\u0e9b\u0eb5\u0e94\u0ec2\u0ead\u0e81\u0eb2\u0e94\u0ec3\u0eab\u0ec9\u0e97\u0eb8\u0e81\u0e84\u0ebb\u0e99\u0ea1\u0eb5\u0eaa\u0ec8\u0ea7\u0e99\u0eae\u0ec8\u0ea7\u0ea1\u0e99\u0ecd\u0eb2\u0ead\u0eb5\u0e81. \u0ec0\u0eae\u0eb7\u0ead\u0ec4\u0e9f\u0ec0\u0eab\u0ebc\u0ebb\u0ec8\u0eb2\u0e99\u0eb5\u0ec9 \u0e96\u0eb7\u0ec0\u0e9b\u0eb1\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e9a\u0eb9\u0e8a\u0eb2\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0eaa\u0eb0\u0ec1\u0e94\u0e87\u0ec0\u0e96\u0eb4\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0e81\u0eb0\u0e95\u0eb1\u0e99\u0e8d\u0eb9\u0eae\u0eb9\u0ec9\u0e9a\u0eb8\u0e99\u0e84\u0eb8\u0e99\u0e95\u0ecd\u0ec8\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2\u0ea5\u0ecd\u0eb2\u0e97\u0eb2\u0e99 \u0e97\u0eb5\u0ec8\u0eab\u0ebc\u0ecd\u0ec8\u0ea5\u0ec9\u0ebd\u0e87\u0e8a\u0eb5\u0ea7\u0eb4\u0e94\u0e8a\u0eb2\u0e94\u0e82\u0ead\u0e87\u0e9c\u0eb9\u0ec9\u0e84\u0ebb\u0e99. \u0e81\u0eb2\u0e99\u0ec4\u0e94\u0ec9\u0e9b\u0eb0\u0eaa\u0ebb\u0e9a\u0e9e\u0ebb\u0e9a\u0e9e\u0ecd\u0ec9\u0e81\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0ea5\u0ea7\u0ea1\u0e95\u0ebb\u0ea7\u0e81\u0eb1\u0e99\u0e82\u0ead\u0e87\u0e8a\u0eb8\u0ea1\u0e8a\u0ebb\u0e99\u0e88\u0eb2\u0e81\u0eab\u0ebc\u0eb2\u0e8d\u0e9a\u0ec9\u0eb2\u0e99 \u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0eaa\u0eb0\u0ec1\u0e94\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0eae\u0eb9\u0ec9\u0e9a\u0eb8\u0e99\u0e84\u0eb8\u0e99\u0e95\u0ecd\u0ec8\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2 \u0e96\u0eb7\u0ec0\u0e9b\u0eb1\u0e99\u0e9e\u0eb2\u0e9a\u0e97\u0eb5\u0ec8\u0edc\u0ec9\u0eb2\u0e9b\u0eb0\u0e97\u0eb1\u0e9a\u0ec3\u0e88\u0ec1\u0e9a\u0e9a\u0eab\u0eb2\u0ead\u0eb1\u0e99\u0e9b\u0ebd\u0e9a\u0e9a\u0ecd\u0ec8\u0ec4\u0e94\u0ec9 \u0e97\u0ec8\u0eb2\u0ea1\u0e81\u0eb2\u0e87\u0e8d\u0eb8\u0e81\u0eaa\u0eb0\u0ec4\u0edd\u0e97\u0eb5\u0ec8\u0e99\u0eb1\u0e9a\u0ea1\u0eb7\u0ec9\u0e99\u0eb1\u0e9a\u0e82\u0eb2\u0e94\u0e81\u0eb2\u0e99\u0ec0\u0e8a\u0eb7\u0ec8\u0ead\u0ea1\u0ec2\u0e8d\u0e87\u0e81\u0eb1\u0e9a\u0e97\u0ecd\u0eb2\u0ea1\u0eb0\u0e8a\u0eb2\u0e94\u0eab\u0ebc\u0eb2\u0e8d\u0e82\u0eb6\u0ec9\u0e99\u0ec0\u0ea5\u0eb7\u0ec9\u0ead\u0e8d\u0ec6.<\/p>\n<figure id=\"attachment_17049\" aria-describedby=\"caption-attachment-17049\" style=\"width: 1280px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17049 size-full\" src=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I1887-copy-Large.jpeg\" alt=\"\" width=\"1280\" height=\"853\" srcset=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I1887-copy-Large.jpeg 1280w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I1887-copy-Large-300x200.jpeg 300w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I1887-copy-Large-1024x682.jpeg 1024w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I1887-copy-Large-768x512.jpeg 768w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I1887-copy-Large-630x420.jpeg 630w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I1887-copy-Large-150x100.jpeg 150w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I1887-copy-Large-696x464.jpeg 696w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I1887-copy-Large-1068x712.jpeg 1068w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><figcaption id=\"caption-attachment-17049\" class=\"wp-caption-text\">\u0e8a\u0eb2\u0ea7\u0e9a\u0ec9\u0eb2\u0e99\u0ec1\u0eab\u0ec8\u0ec0\u0eae\u0eb7\u0ead\u0ec4\u0e9f\u0ec4\u0e9b\u0eab\u0eb2\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb3\u0e82\u0ead\u0e87<\/figcaption><\/figure>\n<h3 class=\"p1\"><strong>\u0e99\u0eb0\u0e84\u0ead\u0e99\u0eab\u0ebc\u0ea7\u0e87\u0ea7\u0ebd\u0e87\u0e88\u0eb1\u0e99:<span class=\"Apple-converted-space\">\u00a0<\/span>\u0eab\u0ebb\u0ea7\u0ec3\u0e88\u0e97\u0eb5\u0ec8\u0e9e\u0ea7\u0ea1\u0ec0\u0e95\u0eb1\u0ec9\u0e99\u0ec1\u0eae\u0e87 \u0ec1\u0ea5\u0eb0 \u0ec0\u0e95\u0eb1\u0ea1\u0ec4\u0e9b\u0e94\u0ec9\u0ea7\u0e8d\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0eb8\u0e81<\/strong><\/h3>\n<p class=\"p1\">\u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0ec0\u0eab\u0eb1\u0e99\u0ec0\u0eae\u0eb7\u0ead\u0ea5\u0ead\u0e8d\u0ea5\u0ec8\u0ead\u0e87\u0e95\u0eb2\u0ea1\u0e81\u0eb0\u0ec1\u0eaa\u0e99\u0ecd\u0ec9\u0eb2\u0ec3\u0e99\u0e99\u0eb0\u0e84\u0ead\u0e99\u0eab\u0ebc\u0ea7\u0e87\u0ea7\u0ebd\u0e87\u0e88\u0eb1\u0e99, \u0ec0\u0eae\u0eb1\u0e94\u0ec3\u0eab\u0ec9\u0ec0\u0e81\u0eb5\u0e94\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0eae\u0eb9\u0ec9\u0eaa\u0eb6\u0e81\u0ec0\u0e96\u0eb4\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0ec1\u0e95\u0e81\u0e95\u0ec8\u0eb2\u0e87\u0e81\u0eb1\u0e99\u0ea2\u0ec8\u0eb2\u0e87\u0ec0\u0eab\u0eb1\u0e99\u0ec4\u0e94\u0ec9\u0e8a\u0eb1\u0e94\u0ec0\u0e88\u0e99\u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0e97\u0ebd\u0e9a\u0e81\u0eb1\u0e9a\u0e82\u0eb0\u0e9a\u0ea7\u0e99\u0ec0\u0eae\u0eb7\u0ead\u0ec4\u0e9f\u0e97\u0eb5\u0ec8\u0e9e\u0ea7\u0ea1\u0ec4\u0eab\u0ebc\u0ea5\u0ec8\u0ead\u0e87\u0ea2\u0eb9\u0ec8\u0ec0\u0e97\u0eb4\u0e87\u0edc\u0ec9\u0eb2\u0e99\u0ecd\u0ec9\u0eb2\u0e97\u0eb2\u0e87\u0e9e\u0eb2\u0e81\u0ec0\u0edc\u0eb7\u0ead \u0ec1\u0e95\u0ec8\u0e97\u0eb1\u0e87\u0eaa\u0ead\u0e87\u0ea5\u0ec9\u0ea7\u0e99\u0ec1\u0e95\u0ec8\u0eaa\u0ec9\u0eb2\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0eab\u0ebc\u0ebb\u0e87\u0ec4\u0eab\u0ebc\u0ec4\u0e94\u0ec9\u0ec0\u0e97\u0ebb\u0ec8\u0eb2\u0e81\u0eb1\u0e99. \u0ec3\u0e99\u0ea1\u0eb7\u0ec9\u0e94\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0e9a\u0eb8\u0e99\u0ec4\u0eab\u0ebc\u0ec0\u0eae\u0eb7\u0ead\u0ec4\u0e9f\u0ea2\u0eb9\u0ec8\u0ec1\u0e82\u0ea7\u0e87\u0eab\u0ebc\u0ea7\u0e87\u0e9e\u0eb0\u0e9a\u0eb2\u0e87, \u0e81\u0ecd\u0ea1\u0eb5\u0e87\u0eb2\u0e99\u0e9a\u0eb8\u0e99\u0e8a\u0ec8\u0ea7\u0e87\u0ec0\u0eae\u0eb7\u0ead\u0e97\u0ec8\u0eb2\u0ea7\u0eb1\u0e94\u0e88\u0eb1\u0e99 (\u0e99\u0eb0\u0e84\u0ead\u0e99\u0eab\u0ebc\u0ea7\u0e87\u0ea7\u0ebd\u0e87\u0e88\u0eb1\u0e99) \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0e88\u0eb1\u0e94\u0e82\u0eb6\u0ec9\u0e99\u0ea2\u0ec8\u0eb2\u0e87\u0e84\u0eb6\u0e81\u0e84\u0eb7\u0ec9\u0e99 \u0ec1\u0ea5\u0eb0 \u0e87\u0ebb\u0e94\u0e87\u0eb2\u0ea1, \u0e9c\u0eb9\u0ec9\u0e84\u0ebb\u0e99\u0e99\u0eb1\u0e9a\u0e9e\u0eb1\u0e99\u0ea1\u0eb2\u0e9a\u0ebd\u0e94\u0eaa\u0eb5\u0e81\u0eb1\u0e99\u0ea2\u0eb9\u0ec8\u0ec1\u0e84\u0ea1\u0e9d\u0eb1\u0ec8\u0e87\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2\u0e82\u0ead\u0e87, \u0e97\u0ec8\u0eb2\u0ea1\u0e81\u0eb2\u0e87\u0e9a\u0eb1\u0e99\u0e8d\u0eb2\u0e81\u0eb2\u0e94\u0e97\u0eb5\u0ec8\u0ec2\u0ead\u0e9a\u0ea5\u0ec9\u0ead\u0ea1\u0e94\u0ec9\u0ea7\u0e8d\u0e81\u0eb4\u0ec8\u0e99\u0e97\u0eb9\u0e9a\u0eab\u0ead\u0ea1, \u0e82\u0eb0\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2\u0e82\u0ead\u0e87\u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0ec4\u0e94\u0ec9\u0e81\u0eb2\u0e8d\u0ea1\u0eb2\u0ec0\u0e9b\u0eb1\u0e99\u0eaa\u0eb0\u0edc\u0eb2\u0ea1\u0e8a\u0ec8\u0ea7\u0e87\u0ec0\u0eae\u0eb7\u0ead \u0e97\u0eb5\u0ec8\u0ec0\u0e95\u0eb1\u0ea1\u0ec4\u0e9b\u0e94\u0ec9\u0ea7\u0e8d\u0eaa\u0ebd\u0e87\u0ec2\u0eae\u0ec8\u0eae\u0ec9\u0ead\u0e87\u0ea2\u0ec8\u0eb2\u0e87\u0ea1\u0ec8\u0ea7\u0e99\u0e8a\u0eb7\u0ec8\u0e99\u0e82\u0ead\u0e87\u0e8a\u0eb2\u0ea7\u0e9a\u0ec9\u0eb2\u0e99.<\/p>\n<p class=\"p2\"><span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p1\">\u0e81\u0eb2\u0e99\u0ec0\u0e94\u0eb5\u0e99\u0e97\u0eb2\u0e87\u0ea1\u0eb2\u0eae\u0ead\u0e94\u0eaa\u0eb0\u0e96\u0eb2\u0e99\u0e97\u0eb5\u0ec8\u0e8a\u0ec8\u0ea7\u0e87\u0ec0\u0eae\u0eb7\u0ead\u0e95\u0eb1\u0ec9\u0e87\u0ec1\u0e95\u0ec8\u0ec0\u0e8a\u0ebb\u0ec9\u0eb2\u0ec6 \u0e9a\u0ecd\u0ec8\u0ec4\u0e94\u0ec9\u0edd\u0eb2\u0e8d\u0e84\u0ea7\u0eb2\u0ea1\u0ea7\u0ec8\u0eb2\u0e88\u0eb0\u0ec4\u0e94\u0ec9\u0e99\u0eb1\u0ec8\u0e87\u0e8a\u0ebb\u0ea1\u0e81\u0eb2\u0e99\u0ec1\u0e82\u0ec8\u0e87\u0ec0\u0eae\u0eb6\u0ead\u0e8d\u0eb2\u0ea7\u0ec2\u0e94\u0e8d\u0e81\u0ebb\u0e87\u0ec3\u0e99\u0e97\u0eb1\u0e99\u0e97\u0eb5 \u0ec0\u0e99\u0eb7\u0ec8\u0ead\u0e87\u0e88\u0eb2\u0e81\u0e81\u0eb4\u0e94\u0e88\u0eb0\u0e81\u0ecd\u0eb2\u0e8a\u0ec8\u0ea7\u0e87\u0ec0\u0eae\u0eb7\u0ead\u0e8d\u0eb2\u0ea7\u0ec1\u0ea1\u0ec8\u0e99\u0e88\u0eb1\u0e94\u0e82\u0eb6\u0ec9\u0e99\u0ec3\u0e99\u0e95\u0ead\u0e99\u0e9a\u0ec8\u0eb2\u0e8d, \u0ec1\u0e95\u0ec8\u0e81\u0ecd\u0ec4\u0e94\u0ec9\u0eaa\u0ecd\u0eb2\u0e9c\u0eb1\u0e94\u0e81\u0eb1\u0e9a\u0e9a\u0eb1\u0e99\u0e8d\u0eb2\u0e81\u0eb2\u0e94\u0ead\u0eb1\u0e99\u0edc\u0ec9\u0eb2\u0e9b\u0eb0\u0e97\u0eb1\u0e9a\u0ec3\u0e88\u0ec0\u0e9b\u0eb1\u0e99\u0e81\u0eb2\u0e99\u0e97\u0ebb\u0e94\u0ec1\u0e97\u0e99. \u0ec0\u0eae\u0eb7\u0ead\u0e8d\u0eb2\u0ea7\u0ec1\u0e95\u0ec8\u0ea5\u0eb0\u0ea5\u0ecd\u0eb2\u0e88\u0eb0\u0e96\u0eb7\u0e81\u0e95\u0ebb\u0e81\u0ec1\u0e95\u0ec8\u0e87\u0e9a\u0ecd\u0ec8\u0e95\u0ec8\u0eb2\u0e87\u0eab\u0e8d\u0eb1\u0e87\u0e81\u0eb1\u0e9a\u0eaa\u0ea7\u0e99\u0e94\u0ead\u0e81\u0ec4\u0ea1\u0ec9\u0ea5\u0ead\u0e8d\u0e9f\u0ec9\u0eb2 \u0ec2\u0e94\u0e8d\u0e9b\u0eb0\u0e94\u0eb1\u0e9a\u0e9b\u0eb0\u0e94\u0eb2\u0e94\u0ec9\u0ea7\u0e8d\u0e94\u0ead\u0e81\u0ec4\u0ea1\u0ec9, \u0e97\u0eb8\u0e87, \u0ec1\u0ea5\u0eb0 \u0e9b\u0ec9\u0eb2\u0e8d\u0e8a\u0eb7\u0ec8 \u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0e9b\u0eb0\u0e81\u0eb2\u0e94\u0ec3\u0eab\u0ec9\u0eae\u0eb9\u0ec9\u0e81\u0ec8\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0edd\u0eb9\u0ec8\u0e9a\u0ec9\u0eb2\u0e99, \u0ea7\u0eb1\u0e94 \u0eab\u0ebc\u0eb7 \u0ead\u0ebb\u0e87\u0e81\u0ead\u0e99\u0e97\u0eb5\u0ec8\u0ec0\u0e9b\u0eb1\u0e99\u0e95\u0ebb\u0ea7\u0ec1\u0e97\u0e99\u0ec3\u0eab\u0ec9\u0ec1\u0e81\u0ec8\u0ec0\u0eae\u0eb7\u0ead\u0ea5\u0ecd\u0eb2\u0e94\u0eb1\u0ec8\u0e87\u0e81\u0ec8\u0eb2\u0ea7. \u0e9a\u0eb1\u0e99\u0e94\u0eb2\u0eaa\u0eb5\u0e9e\u0eb2\u0e8d\u0e88\u0eb0\u0e99\u0eb8\u0ec8\u0e87\u0e8a\u0eb8\u0e94\u0eaa\u0eb5\u0e94\u0ebd\u0ea7\u0e81\u0eb1\u0e99\u0edd\u0ebb\u0e94\u0e97\u0eb5\u0ea1 \u0ec1\u0ea5\u0eb0 \u0ea1\u0eb2\u0e9e\u0ec9\u0ead\u0ea1\u0e81\u0eb1\u0e9a\u0eaa\u0ebd\u0e87\u0eaa\u0ea7\u0e94\u0ea1\u0ebb\u0e99 \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0ea1\u0ebb\u0e99\u0e84\u0eb2\u0e96\u0eb2\u0e97\u0eb5\u0ec8\u0ec4\u0e94\u0ec9\u0e88\u0eb2\u0e81\u0e84\u0eb9\u0e9a\u0eb2\u0ead\u0eb2\u0e88\u0eb2\u0e99\u0e9c\u0eb9\u0ec9\u0e8a\u0ebb\u0e87\u0e84\u0eb8\u0e99\u0ea7\u0eb8\u0e94\u0e97\u0eb4 \u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0eaa\u0ec9\u0eb2\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0ec1\u0e82\u0e87\u0ec1\u0e81\u0ec8\u0e99\u0e97\u0eb2\u0e87\u0e88\u0eb4\u0e94\u0ea7\u0eb4\u0e99\u0e8d\u0eb2\u0e99\u0ec3\u0eab\u0ec9\u0ec1\u0e81\u0ec8\u0e97\u0eb5\u0ea1\u0eaa\u0eb5\u0e9e\u0eb2\u0e8d \u0ec1\u0ea5\u0eb0 \u0eaa\u0ec9\u0eb2\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e81\u0e87\u0e82\u0eb2\u0ea1\u0ec3\u0eab\u0ec9\u0ec1\u0e81\u0ec8\u0e9c\u0eb9\u0ec9\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0eae\u0ec8\u0ea7\u0ea1\u0ec1\u0e82\u0ec8\u0e87\u0e82\u0eb1\u0e99. \u0e97\u0ec8\u0eb2\u0e99\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0eaa\u0ecd\u0eb2\u0e9c\u0eb1\u0e94\u0ec4\u0e94\u0ec9\u0ec0\u0e96\u0eb4\u0e87\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0ead\u0eb1\u0e99\u0e8d\u0eb4\u0ec8\u0e87\u0ec3\u0eab\u0e8d\u0ec8 \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0e9c\u0ebb\u0e99\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e81\u0eb2\u0e99\u0e81\u0eb0\u0e81\u0ebd\u0ea1\u0e9d\u0eb6\u0e81\u0e8a\u0ec9\u0ead\u0ea1 \u0e9a\u0ea7\u0e81\u0e81\u0eb1\u0e9a\u0e84\u0ea7\u0eb2\u0ea1\u0e95\u0eb1\u0ec9\u0e87\u0ec3\u0e88\u0e97\u0eb5\u0ec8\u0eaa\u0eb0\u0eaa\u0ebb\u0ea1\u0ea1\u0eb2\u0ec0\u0e9b\u0eb1\u0e99\u0ec0\u0ea7\u0ea5\u0eb2\u0eab\u0ebc\u0eb2\u0e8d\u0ec0\u0e94\u0eb7\u0ead\u0e99.<\/p>\n<p class=\"p2\"><span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p1\">\u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0e81\u0eb2\u0e99\u0ec1\u0e82\u0ec8\u0e87\u0e82\u0eb1\u0e99\u0ec0\u0eae\u0eb7\u0ead\u0e8a\u0ec8\u0ea7\u0e87\u0ec0\u0ea5\u0eb5\u0ec8\u0ea1\u0ec0\u0e9b\u0eb5\u0e94\u0eaa\u0eb2\u0e81\u0e82\u0eb6\u0ec9\u0e99, \u0ec1\u0e84\u0ea1\u0e9d\u0eb1\u0ec8\u0e87\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2\u0e82\u0ead\u0e87\u0e81\u0ecd\u0e88\u0eb0\u0ec4\u0e94\u0ec9\u0e8d\u0eb4\u0e99\u0ec1\u0e95\u0ec8\u0eaa\u0ebd\u0e87\u0ec2\u0eae\u0ec8\u0eae\u0ec9\u0ead\u0e87\u0e82\u0ead\u0e87\u0e9a\u0eb1\u0e99\u0e94\u0eb2\u0e81\u0ead\u0e87\u0ec0\u0e8a\u0e8d\u0ec1\u0e95\u0ec8\u0ea5\u0eb0\u0e9d\u0ec8\u0eb2\u0e8d. \u0e81\u0ead\u0e87\u0ec0\u0e8a\u0e8d\u0e99\u0eb1\u0e9a\u0e9e\u0eb1\u0e99\u0e84\u0ebb\u0e99\u0eaa\u0ebb\u0ec8\u0e87\u0eaa\u0ebd\u0e87\u0e9b\u0eb0\u0eaa\u0eb2\u0e99\u0e81\u0eb6\u0e81\u0e81\u0ec9\u0ead\u0e87, \u0eaa\u0ebd\u0e87\u0e81\u0ead\u0e87\u0e94\u0eb1\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0e88\u0eb1\u0e87\u0eab\u0ea7\u0eb0 \u0e82\u0eb0\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0ec0\u0eae\u0eb7\u0ead\u0e8a\u0ec8\u0ea7\u0e87\u0e81\u0ecd\u0ea1\u0eb8\u0ec8\u0e87\u0edc\u0ec9\u0eb2\u0eaa\u0eb9\u0ec8\u0ec0\u0eaa\u0eb1\u0ec9\u0e99\u0ec4\u0e8a\u0e94\u0ec9\u0ea7\u0e8d\u0ec3\u0e88\u0ead\u0eb1\u0e99\u0e88\u0ebb\u0e94\u0e88\u0ecd\u0ec8\u0e82\u0ead\u0e87\u0e9a\u0eb1\u0e99\u0e94\u0eb2\u0eaa\u0eb5\u0e9e\u0eb2\u0e8d\u0e97\u0eb5\u0ec8\u0eaa\u0eb2\u0ea1\u0eb1\u0e81\u0e84\u0eb5\u0e81\u0eb1\u0e99\u0ec1\u0e81\u0ea7\u0ec8\u0e87\u0ec4\u0e81\u0ea7\u0ec4\u0ea1\u0ec9\u0e9e\u0eb2\u0e8d\u0e97\u0ea7\u0e99\u0e95\u0eb2\u0ea1\u0e81\u0eb0\u0ec1\u0eaa\u0e99\u0ecd\u0ec9\u0eb2\u0ea2\u0ec8\u0eb2\u0e87\u0eaa\u0eb0\u0eab\u0e87\u0ec8\u0eb2\u0e87\u0eb2\u0ea1 \u0e97\u0eb1\u0e87\u0edc\u0ec9\u0eb2\u0e9b\u0eb0\u0eab\u0ebc\u0eb2\u0e94\u0ec3\u0e88. \u0e9a\u0eb1\u0e99\u0e94\u0eb2\u0eaa\u0eb5\u0e9e\u0eb2\u0e8d\u0e8a\u0eb2\u0e8d, \u0eaa\u0eb5\u0e9e\u0eb2\u0e8d\u0e8d\u0eb4\u0e87 \u0ec1\u0ea5\u0eb0 \u0eaa\u0eb5\u0e9e\u0eb2\u0e8d\u0e8d\u0eb4\u0e87-\u0e8a\u0eb2\u0e8d \u0e95\u0ec8\u0eb2\u0e87\u0e81\u0ecd\u0ec4\u0e94\u0ec9\u0eae\u0eb1\u0e9a\u0e8a\u0ec8\u0ea7\u0e87\u0ec0\u0ea7\u0ea5\u0eb2\u0e97\u0eb5\u0ec8\u0edc\u0ec9\u0eb2\u0e88\u0ebb\u0e94\u0e88\u0ecd\u0eb2. \u0e9c\u0eb9\u0ec9\u0e8a\u0eb0\u0e99\u0eb0\u0e81\u0eb2\u0e99\u0ec1\u0e82\u0ec8\u0e87\u0e82\u0eb1\u0e99 \u0e9a\u0ecd\u0ec8\u0e9e\u0ebd\u0e87\u0ec1\u0e95\u0ec8\u0ec4\u0e94\u0ec9\u0eae\u0eb1\u0e9a\u0e82\u0eb1\u0e99\u0ea5\u0eb2\u0e87\u0ea7\u0eb1\u0e99\u0ec0\u0e97\u0ebb\u0ec8\u0eb2\u0e99\u0eb1\u0ec9\u0e99; \u0ec1\u0e95\u0ec8\u0e9e\u0ea7\u0e81\u0ec0\u0e82\u0ebb\u0eb2\u0e8d\u0eb1\u0e87\u0ec4\u0e94\u0ec9\u0eae\u0eb1\u0e9a\u0eaa\u0eb4\u0e94\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0ead\u0ea7\u0e94\u0ead\u0ec9\u0eb2\u0e87\u0e9c\u0ebb\u0e99\u0e87\u0eb2\u0e99\u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0e88\u0eb0\u0eaa\u0eb7\u0e9a\u0e95\u0ecd\u0ec8\u0e84\u0ebb\u0e87\u0ea2\u0eb9\u0ec8\u0e88\u0ebb\u0e99\u0eae\u0ead\u0e94\u0e87\u0eb2\u0e99\u0e9a\u0eb8\u0e99\u0e8a\u0ec8\u0ea7\u0e87\u0ec0\u0eae\u0eb7\u0ead\u0e99\u0e9b\u0eb5\u0e96\u0eb1\u0e94\u0ec4\u0e9b.<\/p>\n<p class=\"p2\"><span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p1\">\u0e99\u0ead\u0e81\u0e88\u0eb2\u0e81\u0e81\u0eb2\u0e99\u0ec1\u0e82\u0ec8\u0e87\u0e82\u0eb1\u0e99\u0ec0\u0eae\u0eb7\u0ead\u0e8a\u0ec8\u0ea7\u0e87\u0ec1\u0ea5\u0ec9\u0ea7, \u0e8d\u0eb1\u0e87\u0ea1\u0eb5\u0e81\u0eb4\u0e94\u0e88\u0eb0\u0e81\u0ecd\u0eb2\u0e9e\u0eb2\u0ec0\u0e9e\u0eb5\u0e99\u0e95\u0ec8\u0eb2\u0e87\u0ec6 \u0ec0\u0e8a\u0eb1\u0ec8\u0e99: \u0e81\u0eb2\u0e99\u0ea5\u0eb4\u0ec9\u0ea1\u0ea5\u0ead\u0e87\u0e81\u0eb1\u0e9a\u0ea5\u0ebb\u0e94\u0e8a\u0eb2\u0e94\u0e82\u0ead\u0e87\u0e9b\u0eb5\u0ec9\u0e87\u0ec4\u0e81\u0ec8\u0e81\u0eb1\u0e9a\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0eab\u0ebc\u0eb2\u0ea1 \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0e9b\u0eb5\u0ec9\u0e87\u0ea2\u0ec9\u0eb2\u0e87\u0ec3\u0eaa\u0ec8\u0ec0\u0e95\u0ebb\u0eb2\u0e96\u0ec8\u0eb2\u0e99\u0e95\u0eb1\u0ec9\u0e87\u0ea5\u0ebd\u0e99\u0ea5\u0eb2\u0e8d\u0e95\u0eb2\u0ea1\u0eae\u0ec9\u0eb2\u0e99\u0e99\u0ec9\u0ead\u0e8d\u0ec1\u0e84\u0ea1\u0e97\u0eb2\u0e87, \u0e9e\u0ea7\u0e81\u0ec0\u0e94\u0eb1\u0e81\u0e99\u0ec9\u0ead\u0e8d\u0e81\u0ecd\u0ec0\u0e9e\u0eb5\u0e94\u0ec0\u0e9e\u0eb5\u0e99\u0e81\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0eab\u0ebc\u0eb4\u0ec9\u0e99\u0e9b\u0eb0\u0ec0\u0e9e\u0e94\u0e95\u0ec8\u0eb2\u0e87\u0ec6 \u0e9a\u0ecd\u0ec8\u0ea7\u0ec8\u0eb2\u0e88\u0eb0\u0ec0\u0e9b\u0eb1\u0e99\u0ea1\u0ec9\u0eb2\u0edd\u0eb9\u0e99 \u0eab\u0ebc\u0eb7 \u0ead\u0eb7\u0ec8\u0e99\u0ec6, \u0eaa\u0ec8\u0ea7\u0e99\u0e9e\u0eb0\u0eaa\u0ebb\u0e87\u0eaa\u0eb2\u0ea1\u0eb0\u0ec0\u0e99\u0e99\u0e81\u0ecd\u0ea1\u0eb5\u0e9e\u0eb4\u0e97\u0eb5\u0e9c\u0eb9\u0e81\u0ec1\u0e82\u0e99\u0ead\u0ea7\u0e8d\u0e9e\u0ead\u0e99\u0ec1\u0e81\u0ec8\u0ead\u0ead\u0e81\u0e95\u0ebb\u0e99\u0e8d\u0eb2\u0e94\u0ec2\u0e8d\u0ea1 \u0e9e\u0ec9\u0ead\u0ea1\u0e8d\u0eb1\u0e87\u0ea1\u0eb5\u0e84\u0ead\u0e99\u0ec0\u0eaa\u0eb5\u0e94\u0e81\u0eb2\u0e87\u0ec1\u0e88\u0ec9\u0e87\u0e97\u0eb5\u0ec8\u0ec3\u0eab\u0ec9\u0e9a\u0eb1\u0e99\u0ec0\u0ea5\u0e87\u0ec0\u0e9e\u0e87\u0ea2\u0ec8\u0eb2\u0e87\u0ea1\u0ec8\u0ea7\u0e99\u0e8a\u0eb7\u0ec8\u0e99 \u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e9a\u0eb1\u0e99\u0e8d\u0eb2\u0e81\u0eb2\u0e94\u0ec3\u0eab\u0ec9\u0ec1\u0e81\u0ec8\u0e81\u0eb2\u0e99\u0eaa\u0eb0\u0ec0\u0eab\u0ebc\u0eb5\u0ea1\u0eaa\u0eb0\u0eab\u0ebc\u0ead\u0e87\u0e87\u0eb2\u0e99\u0e9a\u0eb8\u0e99\u0e84\u0eb6\u0e81\u0e84\u0eb7\u0ec9\u0e99\u0e95\u0eb0\u0eab\u0ebc\u0ead\u0e94\u0e84\u0eb7\u0e99.<span class=\"Apple-converted-space\">\u00a0 <\/span>\u0e81\u0eb4\u0ec8\u0e99\u0eab\u0ead\u0ea1\u0e82\u0ead\u0e87\u0e97\u0eb9\u0e9a\u0e97\u0ebd\u0e99 \u0e9b\u0eb0\u0eaa\u0ebb\u0ea1\u0e9b\u0eb0\u0eaa\u0eb2\u0e99\u0e81\u0eb1\u0e9a\u0e81\u0eb4\u0ec8\u0e99\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0edc\u0ebb\u0ea1\u0e88\u0eb7\u0e99\u0e81\u0ec9\u0ea7\u0e8d \u0ec1\u0ea5\u0eb0 \u0e9b\u0eb4\u0e94\u0e97\u0ec9\u0eb2\u0e8d\u0e87\u0eb2\u0e99\u0e94\u0ec9\u0ea7\u0e8d\u0ec1\u0eaa\u0e87\u0eaa\u0eb5\u0e88\u0eb2\u0e81\u0e81\u0eb2\u0e99\u0e88\u0eb9\u0e94\u0e9e\u0eb8 \u0eab\u0ebc\u0eb7 \u0e94\u0ead\u0e81\u0ec4\u0ea1\u0ec9\u0ec4\u0e9f.<\/p>\n<p class=\"p1\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17050 size-full\" style=\"text-align: center; font-family: Verdana, BlinkMacSystemFont, -apple-system, 'Segoe UI', Roboto, Oxygen, Ubuntu, Cantarell, 'Open Sans', 'Helvetica Neue', sans-serif;\" src=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I2744-copy-Large.jpeg\" alt=\"\" width=\"1280\" height=\"853\" srcset=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I2744-copy-Large.jpeg 1280w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I2744-copy-Large-300x200.jpeg 300w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I2744-copy-Large-1024x682.jpeg 1024w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I2744-copy-Large-768x512.jpeg 768w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I2744-copy-Large-630x420.jpeg 630w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I2744-copy-Large-150x100.jpeg 150w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I2744-copy-Large-696x464.jpeg 696w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/B79I2744-copy-Large-1068x712.jpeg 1068w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>Fireboats are lit totally by candles and lanterns<\/p>\n<h3 class=\"p1\"><strong>\u0e99\u0ecd\u0ec9\u0eb2\u0eaa\u0ead\u0e87\u0eaa\u0eb2\u0e8d\u0eab\u0ebc\u0ead\u0ea1\u0ea5\u0ea7\u0ea1\u0ec0\u0e9b\u0eb1\u0e99\u0eab\u0ebb\u0ea7\u0ec3\u0e88\u0e94\u0ebd\u0ea7\u0e81\u0eb1\u0e99<\/strong><\/h3>\n<p class=\"p1\">\u0eaa\u0eb4\u0ec8\u0e87\u0e97\u0eb5\u0ec8\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e94\u0eb6\u0e87\u0e94\u0eb9\u0e94\u0ec3\u0e88\u0e9c\u0eb9\u0ec9\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0eae\u0ec8\u0ea7\u0ea1\u0e87\u0eb2\u0e99\u0eab\u0ebc\u0eb2\u0e8d\u0e97\u0eb5\u0ec8\u0eaa\u0eb8\u0e94\u0e81\u0ec8\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0e87\u0eb2\u0e99\u0e9a\u0eb8\u0e99\u0e84\u0eb9\u0ec8\u0ec1\u0e9d\u0e94\u0e94\u0eb1\u0ec8\u0e87\u0e81\u0ec8\u0eb2\u0ea7\u0e81\u0ecd\u0e84\u0eb7 \u0e87\u0eb2\u0e99\u0e9a\u0eb8\u0e99\u0e97\u0eb1\u0e87\u0eaa\u0ead\u0e87\u0ea5\u0ec9\u0ea7\u0e99\u0ec1\u0e95\u0ec8\u0ea1\u0eb5\u0eaa\u0ec8\u0ea7\u0e99\u0e81\u0ec8\u0ebd\u0ea7\u0e9e\u0eb1\u0e99\u0e97\u0eb1\u0e87\u0e95\u0eb7\u0ec8\u0ea1\u0ec0\u0e95\u0eb1\u0ea1\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e81\u0eb1\u0e99\u0ea2\u0ec8\u0eb2\u0e87\u0eaa\u0ebb\u0ea1\u0e9a\u0eb9\u0e99\u0ec1\u0e9a\u0e9a. \u0e82\u0eb0\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0eab\u0ebc\u0ea7\u0e87\u0e9e\u0eb0\u0e9a\u0eb2\u0e87\u0ec4\u0e94\u0ec9\u0ea1\u0ead\u0e9a\u0e9b\u0eb0\u0eaa\u0ebb\u0e9a\u0e81\u0eb2\u0e99\u0ec1\u0eab\u0ec8\u0e87\u0e81\u0eb2\u0e99\u0e84\u0eb4\u0e94\u0e9e\u0eb4\u0e88\u0eb2\u0ea5\u0eb0\u0e99\u0eb2 \u0ec1\u0ea5\u0eb0 \u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e8a\u0eb7\u0ec8\u0ead\u0ea1\u0ec2\u0e8d\u0e87\u0e97\u0eb2\u0e87\u0e88\u0eb4\u0e94\u0ea7\u0eb4\u0e99\u0e8d\u0eb2\u0e99; \u0e97\u0eb1\u0e87\u0e96\u0eb7\u0ec0\u0e9b\u0eb1\u0e99\u0ec2\u0ead\u0e81\u0eb2\u0e94\u0eaa\u0ecd\u0eb2\u0ea5\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e9c\u0ec8\u0ead\u0e99\u0e84\u0eb2\u0e8d \u0ec1\u0ea5\u0eb0 \u0e88\u0ebb\u0e94\u0e88\u0ecd\u0eb2\u0eaa\u0eb4\u0ec8\u0e87\u0eaa\u0ecd\u0eb2\u0e84\u0eb1\u0e99\u0ea2\u0ec8\u0eb2\u0e87\u0ec1\u0e97\u0ec9\u0e88\u0eb4\u0e87. \u0eaa\u0ec8\u0ea7\u0e99\u0e99\u0eb0\u0e84\u0ead\u0e99\u0eab\u0ebc\u0ea7\u0e87\u0ea7\u0ebd\u0e87\u0e88\u0eb1\u0e99\u0e81\u0ecd\u0ec4\u0e94\u0ec9\u0ea1\u0ead\u0e9a\u0eaa\u0eb2\u0e99\u0ec1\u0eab\u0ec8\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0eb8\u0e81\u0ead\u0eb1\u0e99\u0e9a\u0ecd\u0ea5\u0eb4\u0eaa\u0eb8\u0e94 \u0ec1\u0ea5\u0eb0 \u0e81\u0eb2\u0e99\u0eaa\u0eb0\u0ec0\u0eab\u0ebc\u0eb5\u0ea1\u0eaa\u0eb0\u0eab\u0ebc\u0ead\u0e87\u0eae\u0ec8\u0ea7\u0ea1\u0e81\u0eb1\u0e99 \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0eaa\u0eb1\u0e99\u0e8d\u0eb2\u0e99\u0ec0\u0e95\u0eb7\u0ead\u0e99\u0ec3\u0e88\u0ec3\u0eab\u0ec9\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e84\u0eb4\u0e94\u0ec4\u0e94\u0ec9\u0ea7\u0ec8\u0eb2 \u0e8a\u0eb5\u0ea7\u0eb4\u0e94\u0e84\u0ea7\u0e99\u0e94\u0ecd\u0eb2\u0ea5\u0ebb\u0e87\u0e84\u0ebb\u0e87\u0ea2\u0eb9\u0ec8\u0e94\u0ec9\u0ea7\u0e8d\u0e84\u0ea7\u0eb2\u0ea1\u0e9b\u0eb2\u0e96\u0eb0\u0edc\u0eb2 \u0ec1\u0ea5\u0eb0 \u0ea1\u0eb5\u0ec0\u0e9b\u0ebb\u0ec9\u0eb2\u0edd\u0eb2\u0e8d\u0e97\u0eb5\u0ec8\u0ec1\u0e99\u0ec8\u0e99\u0ead\u0e99.<\/p>\n<p class=\"p2\"><span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p1\">\u0e87\u0eb2\u0e99\u0e9a\u0eb8\u0e99\u0e97\u0eb1\u0e87\u0eaa\u0ead\u0e87\u0ea5\u0ec9\u0ea7\u0e99\u0ec1\u0e95\u0ec8\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0edd\u0eb2\u0e8d\u0ead\u0eb1\u0e99\u0ec0\u0ea5\u0eb4\u0e81\u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0eae\u0ec8\u0ea7\u0ea1\u0e81\u0eb1\u0e99 \u0e99\u0eb1\u0ec9\u0e99\u0e81\u0ecd\u0e84\u0eb7: \u0e81\u0eb2\u0e99\u0eaa\u0eb0\u0ec1\u0e94\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0e81\u0eb0\u0e95\u0eb1\u0e99\u0e8d\u0eb9\u0eae\u0eb9\u0ec9\u0e9a\u0eb8\u0e99\u0e84\u0eb8\u0e99\u0e95\u0ecd\u0ec8\u0ec0\u0e88\u0ebb\u0ec9\u0eb2\u0ec1\u0ea1\u0ec8\u0e84\u0ebb\u0e87\u0e84\u0eb2\u0e97\u0eb5\u0ec8\u0eaa\u0eb0\u0e96\u0eb4\u0e94\u0ea2\u0eb9\u0ec8\u0ec3\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2\u0e82\u0ead\u0e87 \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0eaa\u0eb2\u0e8d\u0e99\u0ecd\u0ec9\u0eb2\u0e97\u0eb5\u0ec8\u0eab\u0ebc\u0ecd\u0ec8\u0ea5\u0ec9\u0ebd\u0e87\u0e8a\u0eb5\u0ea7\u0eb4\u0e94\u0e9b\u0eb0\u0e8a\u0eb2\u0e8a\u0ebb\u0e99\u0e9e\u0eb2\u0e8d\u0ec3\u0e99\u0e8a\u0eb2\u0e94, \u0ea5\u0ea7\u0ea1\u0e97\u0eb1\u0e87\u0e81\u0eb2\u0e99\u0ec0\u0e84\u0ebb\u0eb2\u0ea5\u0ebb\u0e9a\u0e99\u0eb1\u0e9a\u0e96\u0eb7\u0eae\u0eb5\u0e94\u0e84\u0ead\u0e87\u0e9b\u0eb0\u0ec0\u0e9e\u0e99\u0eb5\u0e97\u0eb5\u0ec8\u0ec0\u0e8a\u0eb7\u0ec8\u0ead\u0ea1\u0ec2\u0e8d\u0e87\u0ec0\u0ead\u0ebb\u0eb2\u0e8a\u0eb8\u0ea1\u0e8a\u0ebb\u0e99\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0eab\u0eb2\u0e81\u0eb1\u0e99 \u0ec1\u0ea5\u0eb0 \u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0ec3\u0e88\u0e97\u0eb5\u0ec8\u0ea7\u0ec8\u0eb2 \u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0eb8\u0e81\u0ead\u0eb1\u0e99\u0e8d\u0eb4\u0ec8\u0e87\u0ec3\u0eab\u0e8d\u0ec8\u0e97\u0eb5\u0ec8\u0eaa\u0eb8\u0e94\u0ec3\u0e99\u0e8a\u0eb5\u0ea7\u0eb4\u0e94\u0e81\u0ecd\u0ec1\u0ea1\u0ec8\u0e99\u0e81\u0eb2\u0e99\u0e9b\u0ec8\u0ead\u0e8d\u0ea7\u0eb2\u0e87\u0e9b\u0eb0\u0e8a\u0eb2\u0e8a\u0ebb\u0e99\u0ea5\u0eb2\u0ea7\u0e9a\u0ecd\u0ec8\u0e9e\u0ebd\u0e87\u0ec1\u0e95\u0ec8\u0e88\u0eb1\u0e94\u0e87\u0eb2\u0e99\u0e9a\u0eb8\u0e99\u0eaa\u0eb0\u0ec0\u0eab\u0ebc\u0eb5\u0ea1\u0eaa\u0eb0\u0eab\u0ebc\u0ead\u0e87\u0ea1\u0eb7\u0ec9\u0eaa\u0eb4\u0ec9\u0e99\u0eaa\u0eb8\u0e94\u0e82\u0ead\u0e87\u0ea7\u0eb1\u0e99\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e9e\u0eb1\u0e99\u0eaa\u0eb2\u0ec0\u0e97\u0ebb\u0ec8\u0eb2\u0e99\u0eb1\u0ec9\u0e99, \u0ec1\u0e95\u0ec8\u0e8d\u0eb1\u0e87\u0ea1\u0eb5\u0e81\u0eb2\u0e99\u0ec4\u0e95\u0ec9\u0ec0\u0eae\u0eb7\u0ead\u0ec4\u0e9f, \u0e8a\u0ec8\u0ea7\u0e87\u0ec0\u0eae\u0eb7\u0ead, \u0eae\u0ec9\u0ead\u0e87\u0ea5\u0ecd\u0eb2\u0e97\u0ecd\u0eb2\u0ec0\u0e9e\u0e87 \u0ec1\u0ea5\u0eb0 \u0ec1\u0e9a\u0ec8\u0e87\u0e9b\u0eb1\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0eb8\u0e81, \u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e84\u0ebb\u0eb2\u0ea5\u0ebb\u0e9a\u0e99\u0eb1\u0e9a\u0e96\u0eb7 \u0e9b\u0ebd\u0e9a\u0e94\u0eb1\u0ec8\u0e87\u0eaa\u0eb2\u0e8d\u0e99\u0ecd\u0ec9\u0eb2\u0e97\u0eb5\u0ec8\u0e9a\u0ecd\u0ec8\u0ec0\u0e84\u0eb5\u0e8d\u0ea2\u0eb8\u0e94\u0ec4\u0eab\u0ebc.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_17052\" aria-describedby=\"caption-attachment-17052\" style=\"width: 1280px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17052 size-full\" src=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/End-of-Buddhist-lent-13-Large.jpeg\" alt=\"\" width=\"1280\" height=\"853\" srcset=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/End-of-Buddhist-lent-13-Large.jpeg 1280w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/End-of-Buddhist-lent-13-Large-300x200.jpeg 300w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/End-of-Buddhist-lent-13-Large-1024x682.jpeg 1024w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/End-of-Buddhist-lent-13-Large-768x512.jpeg 768w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/End-of-Buddhist-lent-13-Large-630x420.jpeg 630w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/End-of-Buddhist-lent-13-Large-150x100.jpeg 150w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/End-of-Buddhist-lent-13-Large-696x464.jpeg 696w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/End-of-Buddhist-lent-13-Large-1068x712.jpeg 1068w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><figcaption id=\"caption-attachment-17052\" class=\"wp-caption-text\">Rowers must paddle hard and fast to win<\/figcaption><\/figure>\n<figure id=\"attachment_17053\" aria-describedby=\"caption-attachment-17053\" style=\"width: 1280px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17053 size-full\" src=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/End-of-Buddhist-lent-15-Large.jpeg\" alt=\"\" width=\"1280\" height=\"853\" srcset=\"https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/End-of-Buddhist-lent-15-Large.jpeg 1280w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/End-of-Buddhist-lent-15-Large-300x200.jpeg 300w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/End-of-Buddhist-lent-15-Large-1024x682.jpeg 1024w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/End-of-Buddhist-lent-15-Large-768x512.jpeg 768w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/End-of-Buddhist-lent-15-Large-630x420.jpeg 630w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/End-of-Buddhist-lent-15-Large-150x100.jpeg 150w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/End-of-Buddhist-lent-15-Large-696x464.jpeg 696w, https:\/\/champameuanglao.com\/wp-content\/uploads\/2025\/09\/End-of-Buddhist-lent-15-Large-1068x712.jpeg 1068w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><figcaption id=\"caption-attachment-17053\" class=\"wp-caption-text\">A carnival sets up in time for the boat races<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\">\u0e81\u0eb2\u0e99\u0ec0\u0e94\u0eb5\u0e99\u0e97\u0eb2\u0e87:<\/span><\/p>\n<p class=\"p2\"><span class=\"s1\">\u0eaa\u0eb2\u0e8d\u0e81\u0eb2\u0e99\u0e9a\u0eb4\u0e99\u0ea5\u0eb2\u0ea7\u0ec3\u0eab\u0ec9\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e96\u0ec9\u0ebd\u0ea7\u0e9a\u0eb4\u0e99\u0ec4\u0e9b\u0e99\u0eb0\u0e84\u0ead\u0e99\u0eab\u0ebc\u0ea7\u0e87\u0ea7\u0ebd\u0e87\u0e88\u0eb1\u0e99 \u0ec1\u0ea5\u0eb0 \u0eab\u0ebc\u0ea7\u0e87\u0e9e\u0eb0\u0e9a\u0eb2\u0e87\u0e97\u0eb8\u0e81\u0ea7\u0eb1\u0e99 \u0ec2\u0e94\u0e8d\u0ea1\u0eb5\u0e9b\u0eb2\u0e8d\u0e97\u0eb2\u0e87\u0e88\u0eb2\u0e81\u0eab\u0ebc\u0eb2\u0e8d\u0e95\u0ebb\u0ea7\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ec3\u0e99\u0ea5\u0eb2\u0ea7 \u0ec1\u0ea5\u0eb0 \u0e97\u0ebb\u0ec8\u0ea7\u0e9e\u0eb2\u0e81\u0e9e\u0eb7\u0ec9\u0e99<\/span><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u0eaa\u0eb5\u0eaa\u0eb1\u0e99\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ea5\u0eb2\u0ea7\u0e9e\u0eb2\u0e8d\u0eab\u0ebc\u0eb1\u0e87\u0eaa\u0eb4\u0ec9\u0e99\u0eaa\u0eb8\u0e94\u0ec4\u0ea5\u0e8d\u0eb0\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e9e\u0eb1\u0e99\u0eaa\u0eb2 \u0e9a\u0ebb\u0e94\u0ec2\u0e94\u0e8d: \u0ec0\u0e88\u0eaa\u0eb1\u0e99 \u0ec2\u0ea3\u0ea5\u0eb1\u0e99 \u0eae\u0eb9\u0e9a\u0ec2\u0e94\u0e8d: \u0e9e\u0eb9\u0e99\u0e8a\u0eb1\u0e9a \u0ec0\u0e97\u0ea7\u0ebb\u0e87\u0eaa\u0eb2 \u0ec1\u0e9b \u0ec1\u0ea5\u0eb0 \u0eae\u0ebd\u0e9a\u0eae\u0ebd\u0e87\u0ec2\u0e94\u0e8d: \u0ec4\u0e9e\u0e9a\u0eb9\u0e99 \u0e97\u0eb0\u0e99\u0eb0\u0e9a\u0ebb\u0ea7\u0eaa\u0eb5 \u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0eae\u0ead\u0e94\u0e8a\u0ec8\u0ea7\u0e87\u0ec0\u0ea7\u0ea5\u0eb2\u0edc\u0eb6\u0ec8\u0e87, \u0e82\u0eb0\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0e87\u0eb2\u0e99\u0e9a\u0eb8\u0e99\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e9e\u0eb1\u0e99\u0eaa\u0eb2\u0e81\u0ecd\u0eb2\u0ea5\u0eb1\u0e87\u0e88\u0eb0\u0eaa\u0eb4\u0ec9\u0e99\u0eaa\u0eb8\u0e94\u0ea5\u0ebb\u0e87\u0ec3\u0e99\u0e8a\u0ec8\u0ea7\u0e87\u0ec0\u0e94\u0eb7\u0ead\u0e99\u0e95\u0eb8\u0ea5\u0eb2\u0e82\u0ead\u0e87\u0e97\u0eb8\u0e81\u0ec6\u0e9b\u0eb5 \u0ec1\u0ea5\u0eb0 \u0e9b\u0eb0\u0e8a\u0eb2\u0e8a\u0ebb\u0e99\u0e84\u0ebb\u0e99\u0ea5\u0eb2\u0ea7\u0e81\u0ecd\u0e9b\u0eb2\u0e81\u0ebb\u0e94\u0ea7\u0ec8\u0eb2\u0eae\u0eb9\u0ec9\u0eaa\u0eb6\u0e81\u0ec2\u0ea5\u0ec8\u0e87\u0ead\u0ebb\u0e81\u0ec2\u0ea5\u0ec8\u0e87\u0ec3\u0e88\u0eab\u0ebc\u0eb2\u0e8d\u0e82\u0eb6\u0ec9\u0e99. \u0eaa\u0eb2\u0e8d\u0e9d\u0ebb\u0e99\u0ec4\u0e94\u0ec9\u0e9e\u0eb1\u0e94\u0e9e\u0eb2\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2\u0e82\u0ead\u0e87\u0ec3\u0eab\u0ec9\u0ead\u0eb1\u0ec8\u0e87\u0ea5\u0ebb\u0ec9\u0e99\u0e88\u0ebb\u0ea1\u0ec0\u0e95\u0eb1\u0ea1\u0e9d\u0eb1\u0ec8\u0e87\u0e97\u0eb1\u0e87\u0eaa\u0ead\u0e87\u0e9f\u0eb2\u0e81, \u0e82\u0eb0\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0ec0\u0ea5\u0eb5\u0ec8\u0ea1\u0eae\u0ec9\u0ead\u0e99\u0e82\u0eb6\u0ec9\u0e99 \u0eaa\u0ebb\u0ec8\u0e87\u0ec1\u0eaa\u0e87\u0eaa\u0eb5\u0e97\u0ead\u0e87\u0e97\u0ebb\u0ec8\u0ea7\u0e97\u0eb8\u0e81\u0eaa\u0eb2\u0ea5\u0eb0\u0e97\u0eb4\u0e94, \u0ec1\u0ea5\u0eb0 \u0e97\u0ebb\u0ec8\u0ea7\u0e9b\u0eb0\u0ec0\u0e97\u0e94\u0e95\u0ec8\u0eb2\u0e87\u0e81\u0ecd\u0eab\u0ec9\u0eb2\u0e87\u0eab\u0eb2\u0e81\u0eb0\u0e81\u0ebd\u0ea1\u0e88\u0eb1\u0e94\u0e87\u0eb2\u0e99\u0e9a\u0eb8\u0e99\u0eaa\u0eb0\u0ec0\u0eab\u0ebc\u0eb5\u0ea1\u0eaa\u0eb0\u0eab\u0ebc\u0ead\u0e87\u0e81\u0eb1\u0e99\u0ea2\u0ec8\u0eb2\u0e87\u0e8d\u0eb4\u0ec8\u0e87\u0ec3\u0eab\u0e8d\u0ec8\u0e9f\u0ebb\u0e94\u0e9f\u0eb7\u0ec9\u0e99, \u0e97\u0ec8\u0eb2\u0ea1\u0e81\u0eb2\u0e87\u0ec1\u0eaa\u0e87\u0eaa\u0eb5\u0e95\u0eb2\u0ea1\u0eaa\u0eb2\u0e8d\u0e99\u0ecd\u0ec9\u0eb2, \u0ec1\u0e9b\u0ea7\u0ec4\u0e9f \u0ec1\u0ea5\u0eb0 \u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0eab\u0ebc\u0eb7\u0ec9\u0ead\u0ea1\u0ec3\u0eaa\u0eaa\u0eb1\u0e94\u0e97\u0eb2. \u00a0 \u0eaa\u0ecd\u0eb2\u0ea5\u0eb1\u0e9a\u0ea1\u0eb7\u0ec9\u0e97\u0eb5\u0ec8\u0ec0\u0e9b\u0eb1\u0e99\u0eaa\u0eb5\u0ea5\u0eb4\u0ea1\u0eb8\u0e87\u0e84\u0eb8\u0e99\u0e94\u0ebd\u0ea7\u0e81\u0eb1\u0e99\u0e82\u0ead\u0e87\u0e9b\u0eb5\u0e99\u0eb5\u0ec9 \u0ec1\u0ea1\u0ec8\u0e99\u0e81\u0ebb\u0e87\u0e81\u0eb1\u0e9a\u0ea7\u0eb1\u0e99\u0e97\u0eb5 8 \u0e95\u0eb8\u0ea5\u0eb2 \u0e9e\u0eb2\u0e8d\u0eab\u0ebc\u0eb1\u0e87\u0e81\u0eb2\u0e99\u0e9a\u0ecd\u0eb2\u0ec0\u0e9e\u0eb1\u0e99\u0e9e\u0ebd\u0e99\u0e9e\u0eb2\u0ea7\u0eb0\u0e99\u0eb2\u0ec4\u0ea5\u0e8d\u0eb0\u0eaa\u0eb2\u0ea1\u0ec0\u0e94\u0eb7\u0ead\u0e99\u0eaa\u0eb4\u0ec9\u0e99\u0eaa\u0eb8\u0e94\u0ea5\u0ebb\u0e87, \u0ec0\u0e97\u0eaa\u0eb0\u0e81\u0eb2\u0e99\u0e97\u0eb5\u0ec8\u0edc\u0ec9\u0eb2\u0eab\u0ebc\u0ebb\u0e87\u0ec4\u0eab\u0ebc\u0e82\u0ead\u0e87\u0ea5\u0eb2\u0ea7\u0e97\u0eb1\u0e87 2 \u0e87\u0eb2\u0e99\u0e81\u0ecd\u0ec0\u0ea5\u0eb5\u0ec8\u0ea1\u0e95\u0ebb\u0ec9\u0e99\u0e82\u0eb6\u0ec9\u0e99\u0e97\u0eb5\u0ec8\u0ec1\u0e84\u0ea1\u0e9d\u0eb1\u0ec8\u0e87\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2\u0e82\u0ead\u0e87 \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0eaa\u0eb2\u0e8d\u0e99\u0ecd\u0ec9\u0eb2\u0e97\u0eb5\u0ec8\u0ec3\u0eab\u0e8d\u0ec8\u0e97\u0eb5\u0ec8\u0eaa\u0eb8\u0e94\u0ec3\u0e99\u0ea5\u0eb2\u0ea7. \u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0eab\u0ea7\u0e99\u0e81\u0eb1\u0e9a\u0ea1\u0eb2\u0e97\u0eb5\u0ec8\u0ec1\u0e82\u0ea7\u0e87\u0eab\u0ebc\u0ea7\u0e87\u0e9e\u0eb0\u0e9a\u0eb2\u0e87, \u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0eab\u0ebc\u0ea7\u0e87\u0e9a\u0eb9\u0eae\u0eb2\u0e99\u0ec1\u0eab\u0ec8\u0e87\u0e99\u0eb5\u0ec9\u0ec4\u0e94\u0ec9\u0e81\u0eb2\u0e8d\u0ec0\u0e9b\u0eb1\u0e99\u0e94\u0eb4\u0e99\u0ec1\u0e94\u0e99\u0ea1\u0eb0\u0eab\u0eb1\u0e94\u0eaa\u0eb0\u0e88\u0eb1\u0e99\u0ec1\u0eab\u0ec8\u0e87\u0eae\u0eb8\u0ec8\u0e87\u0eaa\u0eb0\u0eab\u0ebc\u0ebb\u0ea7. \u0ea2\u0eb9\u0ec8\u0eab\u0ec8\u0eb2\u0e87\u0e88\u0eb2\u0e81\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0eab\u0ebc\u0ea7\u0e87\u0e9e\u0eb0\u0e9a\u0eb2\u0e87\u0ec4\u0e9b\u0e97\u0eb2\u0e87\u0e97\u0eb4\u0e94\u0ec3\u0e95\u0ec9\u0e9e\u0ebd\u0e87 40 \u0e99\u0eb2\u0e97\u0eb5\u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0ec0\u0e94\u0eb5\u0e99\u0e97\u0eb2\u0e87\u0ec2\u0e94\u0e8d\u0ec0\u0eae\u0eb7\u0ead\u0e9a\u0eb4\u0e99, \u0e81\u0ecd\u0ea1\u0eb5\u0e99\u0eb0\u0e84\u0ead\u0e99\u0eab\u0ebc\u0ea7\u0e87\u0ea7\u0ebd\u0e87\u0e88\u0eb1\u0e99\u0e97\u0eb5\u0ec8\u0e9e\u0ea7\u0ea1\u0e9f\u0ebb\u0e94\u0eaa\u0eb0\u0e99\u0eb1\u0ec8\u0e99\u0e94\u0ec9\u0ea7\u0e8d\u0eaa\u0ebd\u0e87\u0ec0\u0eae\u0eb7\u0ead\u0e8a\u0ec8\u0ea7\u0e87\u0e9b\u0eb0\u0eaa\u0eb2\u0e99\u0e81\u0eb1\u0e9a\u0eaa\u0ebd\u0e87\u0ec2\u0eae\u0ec8\u0eae\u0ec9\u0ead\u0e87\u0e82\u0ead\u0e87\u0e9a\u0eb1\u0e99\u0e94\u0eb2\u0e99\u0eb1\u0e81\u0e8a\u0ebb\u0ea1-\u0ec0\u0e8a\u0e8d\u0ea2\u0eb9\u0ec8\u0ec1\u0e84\u0ea1\u0e9d\u0eb1\u0ec8\u0e87\u0ec1\u0ea1\u0ec8\u0e99\u0ecd\u0ec9\u0eb2, \u0ec1\u0e95\u0ec8\u0e81\u0eb2\u0e99\u0eaa\u0eb0\u0ec0\u0eab\u0ebc\u0eb5\u0ea1\u0eaa\u0eb0\u0eab\u0ebc\u0ead\u0e87\u0e87\u0eb2\u0e99\u0e9a\u0eb8\u0e99\u0e94\u0eb1\u0ec8\u0e87\u0e81\u0ec8\u0eb2\u0ea7\u0ec3\u0e99\u0ec1\u0e95\u0ec8\u0ea5\u0eb0\u0e84\u0eb1\u0ec9\u0e87 \u0ea5\u0ec9\u0ea7\u0e99\u0ec1\u0e95\u0ec8\u0eaa\u0eb0\u0e97\u0ec9\u0ead\u0e99\u0ec3\u0eab\u0ec9\u0ec0\u0eab\u0eb1\u0e99\u0ec0\u0e96\u0eb4\u0e87\u0e88\u0eb4\u0e94\u0ea7\u0eb4\u0e99\u0e8d\u0eb2\u0e99\u0e82\u0ead\u0e87\u0e9b\u0eb0\u0e8a\u0eb2\u0e8a\u0ebb\u0e99\u0ea5\u0eb2\u0ea7\u0e97\u0eb5\u0ec8\u0eaa\u0eb0\u0ec1\u0e94\u0e87\u0ead\u0ead\u0e81\u0ec3\u0e99\u0eab\u0ebc\u0eb2\u0e8d\u0ec1\u0e87\u0ec8\u0ea1\u0eb8\u0ea1. &nbsp; &nbsp; \u0eab\u0ebc\u0ea7\u0e87\u0e9e\u0eb0\u0e9a\u0eb2\u0e87: \u0e9a\u0ec8\u0ead\u0e99\u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0ec1\u0eaa\u0e87\u0ec4\u0e9f\u0ea5\u0ead\u0e8d\u0ea5\u0ec8\u0ead\u0e87\u0ec0\u0e97\u0eb4\u0e87\u0edc\u0ec9\u0eb2\u0e99\u0ecd\u0ec9\u0eb2 \u0e9a\u0ecd\u0ec8\u0ea1\u0eb5\u0eaa\u0eb4\u0ec8\u0e87\u0ec3\u0e94\u0e97\u0eb5\u0ec8\u0e88\u0eb0\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e81\u0eb0\u0e81\u0ebd\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0e9e\u0ec9\u0ead\u0ea1\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0e95\u0ec9\u0ead\u0e99\u0eae\u0eb1\u0e9a\u0ec1\u0e82\u0e81\u0e9a\u0ec9\u0eb2\u0e99\u0ec1\u0e82\u0e81\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e97\u0eb5\u0ec8\u0ec0\u0e94\u0eb5\u0e99\u0e97\u0eb2\u0e87\u0ea1\u0eb2\u0e97\u0ec8\u0ebd\u0ea7\u0e8a\u0ebb\u0ea1\u0eab\u0ebc\u0ea7\u0e87\u0e9e\u0eb0\u0e9a\u0eb2\u0e87\u0ec4\u0e94\u0ec9\u0ea2\u0ec8\u0eb2\u0e87\u0eaa\u0ebb\u0ea1\u0e9a\u0eb9\u0e99\u0ec1\u0e9a\u0e9a\u0e97\u0ebd\u0ea1\u0e97\u0eb1\u0e99\u0ec0\u0e97\u0ebb\u0ec8\u0eb2\u0e87\u0eb2\u0e99\u0e9a\u0eb8\u0e99\u0ec4\u0eab\u0ebc\u0ec0\u0eae\u0eb7\u0ead\u0ec4\u0e9f. \u0ec3\u0e99\u0e82\u0eb0\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0e94\u0ea7\u0e87\u0e95\u0eb2\u0ec0\u0ea7\u0eb1\u0e99\u0e9e\u0ea7\u0ea1\u0ea5\u0eb2\u0ea5\u0eb1\u0e9a\u0eaa\u0eb9\u0ec8\u0e82\u0ead\u0e9a\u0e9f\u0ec9\u0eb2\u0e9f\u0eb2\u0e81\u0edc\u0ec8\u0ea7\u0e8d\u0e9e\u0eb9\u0eaa\u0eb9\u0e87\u0ec0\u0e94\u0eb1\u0ec8\u0e99\u0ec0\u0edc\u0eb7\u0ead\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ea1\u0ecd\u0ea5\u0eb0\u0e94\u0ebb\u0e81\u0ec2\u0ea5\u0e81\u0e82\u0ead\u0e87\u0ead\u0ebb\u0e87\u0e81\u0eb2\u0e99 UNESCO \u0ec1\u0eab\u0ec8\u0e87\u0e99\u0eb5\u0ec9, \u0e81\u0ecd\u0ea1\u0eb5\u0e9a\u0eb2\u0e87\u0eaa\u0eb4\u0ec8\u0e87\u0e97\u0eb5\u0ec8\u0edc\u0ec9\u0eb2\u0ead\u0eb1\u0e94\u0eaa\u0eb0\u0e88\u0eb1\u0e99\u0ec4\u0e94\u0ec9\u0ec0\u0ea5\u0eb5\u0ec8\u0ea1\u0e9b\u0eb2\u0e81\u0ebb\u0e94\u0e95\u0ebb\u0ea7\u0e82\u0eb6\u0ec9\u0e99. \u0e81\u0eb2\u0e99\u0e97\u0eb5\u0ec8\u0ec1\u0eaa\u0e87\u0ec4\u0e9f\u0e9f\u0ec9\u0eb2\u0e88\u0eb0\u0e84\u0ec8\u0ead\u0e8d\u0e94\u0eb1\u0e9a\u0ea1\u0ead\u0e94\u0ea5\u0ebb\u0e87\u0ec0\u0e97\u0eb7\u0ec8\u0ead\u0ea5\u0eb0\u0e94\u0ea7\u0e87\u0e99\u0eb1\u0ec9\u0e99 \u0e9a\u0ecd\u0ec8\u0ec1\u0ea1\u0ec8\u0e99\u0ec0\u0eab\u0e94\u0e81\u0eb2\u0e99\u0e9a\u0eb1\u0e87\u0ec0\u0ead\u0eb5\u0e99\u0ec1\u0e95\u0ec8\u0ea2\u0ec8\u0eb2\u0e87\u0ec3\u0e94 [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":17049,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[107],"tags":[840,1112,1111,1113,159,119,1115,1117,1121,157,1114,849,1119,1118,1116,1120],"class_list":["post-17047","post","type-post","status-publish","format-standard","has-post-thumbnail","category-festival","tag-fire","tag-fireboats","tag-heua-fai","tag-lent","tag-luang-prabang","tag-mekong","tag-1115","tag-1117","tag-1121","tag-157","tag-1114","tag-849","tag-1119","tag-1118","tag-1116","tag-1120"],"_links":{"self":[{"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/posts\/17047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/comments?post=17047"}],"version-history":[{"count":6,"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/posts\/17047\/revisions"}],"predecessor-version":[{"id":17059,"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/posts\/17047\/revisions\/17059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/media\/17049"}],"wp:attachment":[{"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/media?parent=17047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/categories?post=17047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/champameuanglao.com\/la\/wp-json\/wp\/v2\/tags?post=17047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}